{"id":162629,"date":"2020-01-10T08:50:55","date_gmt":"2020-01-10T08:50:55","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2020\/01\/10\/se-suicida-creador-de-ugly-betty\/"},"modified":"2020-01-10T08:50:55","modified_gmt":"2020-01-10T08:50:55","slug":"se-suicida-creador-de-ugly-betty","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2020\/01\/10\/se-suicida-creador-de-ugly-betty\/","title":{"rendered":"Se suicida creador de Ugly Betty"},"content":{"rendered":"<p>Silvio Horta, creador de la exitosa versi&oacute;n estadounidense de la serie &lsquo;Yo soy Betty la fea&rsquo;, &lsquo;Ugly Betty&rsquo;, fue encontrado muerto en un cuarto de hotel en Miami, con una herida de bala aparentemente autoinfligida.<\/p>\n<p>De acuerdo con el m&eacute;dico forense del condado de Miami-Dade, citado por la revista Variety, Horta, de 45 a&ntilde;os, se suicid&oacute; este martes de un tiro. El medio asegur&oacute; que un representante del productor confirm&oacute; su deceso, pero se neg&oacute; a comentar m&aacute;s detalles.<\/p>\n<p>La familia de Horta emiti&oacute; un comunicado en el que afirm&oacute; que el creador sosten&iacute;a una &ldquo;constante lucha contra la adicci&oacute;n y depresi&oacute;n&rdquo; y lo describe como un &ldquo;hombre amable y bueno&rdquo;.<\/p>\n<p>La popular serie&nbsp;<strong>&lsquo;Ugly Betty&rsquo;&nbsp;<\/strong>se emiti&oacute; en Estados Unidos durante cuatro temporadas, de 2006 a 2010, estelarizada por&nbsp;<strong>America Ferrera<\/strong>. El programa, una adaptaci&oacute;n de la telenovela colombiana &lsquo;Betty la fea&rsquo;, tambi&eacute;n tuvo su versi&oacute;n mexicana.<\/p>\n<p>La actriz America Ferrera public&oacute; en su cuenta de&nbsp;<strong>Instagram<\/strong>: &ldquo;Su talento y creatividad me trajeron a m&iacute; y a muchos otros tanta alegr&iacute;a y luz&rdquo;.<\/p>\n<p>La serie, que narra la historia de &lsquo;<strong>Betty Su&aacute;rez<\/strong>&lsquo;, una mexicana-americana que trabaja en una revista de moda de Nueva York, gan&oacute; dos Globos de Oro, uno por la Mejor Comedia y otro por la actuaci&oacute;n de Ferrera.<\/p>\n<p>La telenovela original fue escrita por el colombiano&nbsp;<a href=\"https:\/\/lopezdoriga.com\/entretenimiento\/murio-fernando-gaitan-creador-de-betty-la-fea\/\" rel=\"noopener noreferrer\" target=\"_blank\"><strong>Fernando Gait&aacute;n<\/strong>, quien muri&oacute; en 2019.<\/a><\/p>\n<p>Con informaci&oacute;n de Notimex<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se suicida creador de Ugly Betty<\/p>\n","protected":false},"author":1,"featured_media":162630,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[219],"tags":[11072],"class_list":["post-162629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos","tag-bety-la-fea"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2020\/01\/1578671455_uglybetty.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/162629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=162629"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/162629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/162630"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=162629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=162629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=162629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}