{"id":160019,"date":"2020-03-09T15:02:06","date_gmt":"2020-03-09T15:02:06","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2020\/03\/09\/mantiene-comuna-proceso-de-compra-de-seguro-para-vivienda-tesorero\/"},"modified":"2020-03-09T15:02:06","modified_gmt":"2020-03-09T15:02:06","slug":"mantiene-comuna-proceso-de-compra-de-seguro-para-vivienda-tesorero","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2020\/03\/09\/mantiene-comuna-proceso-de-compra-de-seguro-para-vivienda-tesorero\/","title":{"rendered":"Mantiene Comuna proceso de compra de seguro para vivienda: Tesorero"},"content":{"rendered":"<p>Ser&aacute; Oficial&iacute;a Mayor del Ayuntamiento de Hermosillo, quien decida qu&eacute; aseguradora ser&aacute; la que sea contratada para adquirir seguros para viviendas, dijo Daniel S&aacute;nchez Gonz&aacute;lez.<\/p>\n<p>El tesorero municipal, mencion&oacute; que ese tema que fue abordado desde el a&ntilde;o pasado por la alcaldesa C&eacute;lida L&oacute;pez C&aacute;rdenas, sigue en pie, pero todo depender&aacute; de cual aseguradora v&iacute;a licitaci&oacute;n p&uacute;blica, sea la que mejores condiciones le d&eacute; a la ciudad y de esa forma, se adquiera de nuevo el seguro para viviendas en Hermosillo.<\/p>\n<p>&nbsp;&ldquo;Est&aacute; todav&iacute;a en proceso de compra, es tardado, el gobierno es tardado para comprar. Va a ser una licitaci&oacute;n, ya es parte de la oficial&iacute;a ese tema, Tesorer&iacute;a lo solicita y Oficialia lo contrata, y ah&iacute; ya es la mejor propuesta&rdquo;, explic&oacute;.<\/p>\n<p>El tesorero municipal precis&oacute;, no conocer el monto por el cual se habr&aacute; de contratar ese seguro para viviendas, pero si confi&oacute; que ser&aacute; de beneficio para todo aquel ciudadano que sea cumplido en sus prediales y a la vez tener protegidas sus casas en el caso de alg&uacute;n accidente o siniestro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MANTIENE COMUNA PROCESO DE COMPRA DE SEGURO PARA VIVIENDA: TESORERO<\/p>\n","protected":false},"author":1,"featured_media":160020,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[910],"class_list":["post-160019","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-tesoreria"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2020\/03\/1583791326_20181130113725_135.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/160019","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=160019"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/160019\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/160020"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=160019"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=160019"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=160019"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}