{"id":159587,"date":"2020-03-18T15:28:42","date_gmt":"2020-03-18T15:28:42","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2020\/03\/18\/thalia-confiesa-trastorno-que-padece-desde-joven\/"},"modified":"2020-03-18T15:28:42","modified_gmt":"2020-03-18T15:28:42","slug":"thalia-confiesa-trastorno-que-padece-desde-joven","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2020\/03\/18\/thalia-confiesa-trastorno-que-padece-desde-joven\/","title":{"rendered":"Thalia confiesa trastorno que padece desde joven"},"content":{"rendered":"<p>Este 17 de marzo y a prop&oacute;sito de la psicosis que ha generado en la gente la , <strong>Thal&iacute;a<\/strong> decidi&oacute; &ldquo;salir del cl&oacute;set&rdquo; y confesar a sus seguidores en redes sociales que desde joven padece trastorno obsesivo-compulsivo que, entre otras cosas, le hace realizar varios rituales de limpieza varias veces al d&iacute;a.<\/p>\n<p>Adem&aacute;s de su mensaje, la cantante y actriz mexicana public&oacute; un video en el que representa la reacci&oacute;n que podr&iacute;a tener la gente al escuchar que una persona cercana estornuda: correr al ba&ntilde;o a lavarse las manos, desinfectarse la cara y cepillarse a conciencia los dientes.<\/p>\n<div id=\"outstream_article\" data-id=\"56\" data-m=\"{&quot;i&quot;:56,&quot;p&quot;:54,&quot;n&quot;:&quot;article-inlineOutstreamAd&quot;,&quot;t&quot;:&quot;inlineOutstreamAd&quot;,&quot;o&quot;:2}\">&nbsp;<\/div>\n<p>&ldquo;La mayor parte de mi vida he vivido controlando el #trastornoobsesivocompulsivo que desde joven fui desarrollando. No por nada mi gente m&aacute;s cercana me llama #howardhughes. Han sido a&ntilde;os de control mental y analizar detonadores emocionales para controlar esta complicaci&oacute;n.<\/p>\n<p>&ldquo;Lavarme las manos constantemente, abrir y cerrar las llaves del agua, tocar las manijas de las puertas con un papel y un sin fin de rituales de limpieza han sido una constante para m&iacute;. Tranquilos, la obsesi&oacute;n causa angustia y estresa. Solo s&eacute; consciente de tu entorno, l&aacute;vate tus manos frecuentemente o usa tu Purell y evita tocar superficies met&aacute;licas en lugares p&uacute;blicos. &iexcl;Evita lugares p&uacute;blicos!&rdquo;, comparti&oacute; <strong>Thal&iacute;a<\/strong>.<\/p>\n<p>En esta publicaci&oacute;n la estrella hizo un llamado a ser muy estrictos con la limpieza a&uacute;n en las casas para evitar cualquier imprevisto de salud, pero todo siempre guardando la calma para evitar el estr&eacute;s.<\/p>\n<p>ha sido de las estrellas que m&aacute;s publicaciones ha hecho sobre el covid-19 desde que se declar&oacute; el estado de emergencia en Estados Unidos, siempre haciendo un llamado a ser responsable y a mantener la calma.<\/p>\n<p>&ldquo;Estos son tiempos para estar tranquilos dentro del caos. Estos son tiempos de buscar la paz, la estabilidad, el amor y la fe. S&iacute;, lo que est&aacute; pasando es real, pero tenemos la responsabilidad de mantener la calma y la paz, especialmente si tenemos chiquitos en casa, si somos cuidadores&rdquo;, dice <strong>Thal&iacute;a<\/strong> en uno de sus m&aacute;s recientes videos.<\/p>\n<p>De acuerdo con el <a href=\"https:\/\/www.nimh.nih.gov\/health\/topics\/obsessive-compulsive-disorder-ocd\/index.shtml\" target=\"_blank\" data-id=\"57\" data-m=\"{&quot;i&quot;:57,&quot;p&quot;:54,&quot;n&quot;:&quot;partnerLink&quot;,&quot;y&quot;:24,&quot;o&quot;:3}\" rel=\"noopener\">Instituto Nacional de Salud Mental<\/a> estadounidense, se trata de un trastorno com&uacute;n, cr&oacute;nico y duradero en el que una persona tiene pensamientos (obsesiones) y \/ o comportamientos (compulsiones) incontrolables y recurrentes que siente la necesidad de repetir una y otra vez.<\/p>\n<p>Estos pensamientos y comportamientos pueden interferir con todos los aspectos de la vida, como el trabajo, la escuela y las relaciones personales; entre ellos se encuentran: miedo a los g&eacute;rmenes o la contaminaci&oacute;n, pensamientos agresivos hacia los otros o ellos mismos, limpieza excesiva, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Thalia confiesa trastorno que padece desde joven <\/p>\n","protected":false},"author":1,"featured_media":159588,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[219],"tags":[2544],"class_list":["post-159587","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos","tag-thalia"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2020\/03\/1584570522_SOPHTDBPIJC6RH2CVJAIAXBTFY.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/159587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=159587"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/159587\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/159588"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=159587"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=159587"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=159587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}