{"id":15529,"date":"2014-07-29T14:31:10","date_gmt":"2014-07-29T14:31:10","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/07\/29\/promover-jorge-suilo-orozco-desarrollo-sustentable-para-sonora-2\/"},"modified":"2014-07-29T14:31:10","modified_gmt":"2014-07-29T14:31:10","slug":"promover-jorge-suilo-orozco-desarrollo-sustentable-para-sonora-2","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/07\/29\/promover-jorge-suilo-orozco-desarrollo-sustentable-para-sonora-2\/","title":{"rendered":"Promover&aacute; Jorge Suilo Orozco desarrollo sustentable para Sonora&#8207;"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><strong><span>Hermosillo, Son., 29 de Julio &nbsp;de 2014<\/span><\/strong><span>.- Lograr un sano equilibrio entre el desarrollo econ&oacute;mico y el cuidado del medio ambiente, es uno de los objetivos primordiales del Gobierno Federal, manifest&oacute; el Delegado de Semarnat en Sonora, Jorge Andr&eacute;s Suilo Orozco. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>Y para lograr el desarrollo sustentable, dijo, que es indispensable el acercamiento con empresarios ya instalados o aquellos que planeen abrir alguna industria en la regi&oacute;n, a fin de que respeten los reglamentos ambientales existentes.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&ldquo;Dentro del Plan Nacional de Desarrollo del Presidente Enrique Pe&ntilde;a Nieto se instruye a impulsar y orientar un crecimiento verde incluyente y facilitador que preserve nuestro patrimonio natural al mismo tiempo que genere riqueza, competitividad y empleo&rdquo;, se&ntilde;al&oacute; Suilo Orozco. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>Explic&oacute; que a nivel nacional existe el&nbsp; Programa Nacional de Auditoria Ambiental (PNAA), donde se reconoce a empresas que cumplen con la normatividad ambiental dentro de sus procesos de producci&oacute;n.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>Es, a trav&eacute;s de la certificaci&oacute;n, como el Gobierno Federal reconoce al empresario por su respeto a las normas ecol&oacute;gicas y su entusiasmo decidido en la conservaci&oacute;n del medio ambiente, explic&oacute; el Delegado Federal. &nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&ldquo;Los resultados siempre ser&aacute;n mejores si trabajan, de manera coordinada, autoridad y sociedad; hasta el momento son 86 empresas que ya cuentan con su certificaci&oacute;n&rdquo;, manifest&oacute; el Delegado Federal. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>Las empresas se inscriben de manera voluntaria al Programa Nacional de Auditor&iacute;a Ambiental para someter sus procesos de producci&oacute;n a una auditor&iacute;a donde se detectan las &aacute;reas de oportunidad en cuanto al medio ambiente.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>&nbsp;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"margin-bottom: 0.0001pt;text-align: justify\"><span>Para todos aquellos interesados en certificarse como Industria Limpia pueden solicitar el tr&aacute;mite a la Delegaci&oacute;n de Profepa en Sonora, que se ubica en Solidaridad y Colosio, Edificio B, Segundo Piso o llamar al tel&eacute;fono 2175454 para mayor informaci&oacute;n.&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Promover&aacute; Jorge Suilo Orozco desarrollo sustentable para Sonora&#8207;<\/p>\n","protected":false},"author":1,"featured_media":15530,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[187],"class_list":["post-15529","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-semarnat"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1406669470_Foto290714.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/15529","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=15529"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/15529\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/15530"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=15529"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=15529"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=15529"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}