{"id":15505,"date":"2014-07-08T09:52:26","date_gmt":"2014-07-08T09:52:26","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/07\/08\/por-qu-vot-en-contra-de-la-ley-telecom-pancho-brquez-2\/"},"modified":"2014-07-08T09:52:26","modified_gmt":"2014-07-08T09:52:26","slug":"por-qu-vot-en-contra-de-la-ley-telecom-pancho-brquez-2","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/07\/08\/por-qu-vot-en-contra-de-la-ley-telecom-pancho-brquez-2\/","title":{"rendered":"&quot;Por qu&eacute; vot&eacute; en contra de la Ley Telecom&#8207;: Pancho B&uacute;rquez"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">El pasado 4 de julio, se vot&oacute; la Ley Secundaria en Telecomunicaciones en el Senado. Vot&eacute; en contra de ella.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">A pesar de los grandes avances en cuanto a beneficios para el consumidor en telefon&iacute;a e internet (m&aacute;s competidores, mejores precios y servicios, eliminaci&oacute;n de Larga Distancia y roaming) se mantienen privilegios para el monopolio de TV en todas sus modalidades (abierta,&nbsp; cable y satelital).<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">Estos beneficios se alcanzaron gracias al PAN que durante a&ntilde;os han enfrentado esta lucha, mismos que se hab&iacute;an negado mientras el PRI fue oposici&oacute;n.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">Sin embargo, la Ley Telecom tal como se aprob&oacute; por mayor&iacute;a, tiene grandes fallas:<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">&middot;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Premia al monopolio en TV satelital y por cable, al no ponerle l&iacute;mites para que siga creciendo y monopolizando.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">&middot;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; No respeta la redacci&oacute;n de la constituci&oacute;n, al definir preponderancia por sector.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">&middot;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Disminuye la capacidad del &oacute;rgano regulador antimonopolio (IFT)<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">Vot&eacute; en contra de la Ley Secundaria en Telecomunicaciones por los enormes efectos negativos&nbsp; que tendr&aacute; en la vida del pa&iacute;s: la protecci&oacute;n sin l&iacute;mite al monopolio de TV sin duda afectar&aacute; la calidad informativa para generar opini&oacute;n p&uacute;blica, lo que da lugar a una alianza pol&iacute;tica entre el gobierno federal, el PRI y el monopolio televisivo, con la consecuente amenaza a la democracia en M&eacute;xico.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">En una balanza entre los efectos econ&oacute;micos en telecomunicaciones y los efectos pol&iacute;ticos en la vida democr&aacute;tica de M&eacute;xico, en conciencia decid&iacute; votar en contra de Ley Telecom.<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">Comparto contigo esta opini&oacute;n. Cordialmente,<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">&nbsp;<\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0px;font-family: Arial, Helvetica, sans-serif;font-size: 12px\"><strong style=\"margin: 0px\">Sen. Pancho B&uacute;rquez<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado 4 de julio, se vot&oacute; la Ley Secundaria en Telecomunicaciones en el Senado. Vot&eacute; en contra de ella.<\/p>\n","protected":false},"author":1,"featured_media":15506,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[524],"class_list":["post-15505","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-pancho-burquez"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2025\/01\/1404838346_pancho-burquez-2013.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/15505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=15505"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/15505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/15506"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=15505"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=15505"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=15505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}