{"id":154439,"date":"2020-07-03T23:07:16","date_gmt":"2020-07-03T23:07:16","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2020\/07\/03\/supervisa-celida-lopez-filtros-preventivos-en-hermosillo\/"},"modified":"2020-07-03T23:07:16","modified_gmt":"2020-07-03T23:07:16","slug":"supervisa-celida-lopez-filtros-preventivos-en-hermosillo","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2020\/07\/03\/supervisa-celida-lopez-filtros-preventivos-en-hermosillo\/","title":{"rendered":"Supervisa Celida Lopez filtros preventivos en Hermosillo"},"content":{"rendered":"<p style=\"font-size: 14px;line-height: normal;font-family: Verdana\"><strong>Hermosillo, Sonora, a 3 de julio de 2020.-<\/strong>&nbsp;La alcaldesa Celida L&oacute;pez C&aacute;rdenas supervis&oacute; el filtro preventivo y m&oacute;dulo de Brigadas de Vida ubicados sobre la calle Rosales, parte fundamental de la estrategia del Ayuntamiento de Hermosillo para coadyuvar a la mitigaci&oacute;n de la propagaci&oacute;n de Covid-19 en el Municipio.<\/p>\n<p style=\"font-size: 14px;line-height: normal;font-family: Verdana;min-height: 17px\">&nbsp;<\/p>\n<p style=\"font-size: 14px;line-height: normal;font-family: Verdana\">La Presidenta Municipal atestigu&oacute; el trabajo de los oficiales de la Polic&iacute;a Municipal que solicitan a los automovilistas el permiso de tr&aacute;nsito para movilidad vehicular extempor&aacute;neo a partir de las 18:00 horas. En el mismo sitio, Bomberos apoya en la tarea de exhortar a las personas a quedarse en casa.<\/p>\n<p style=\"font-size: 14px;line-height: normal;font-family: Verdana;min-height: 17px\">&nbsp;<\/p>\n<p style=\"font-size: 14px;line-height: normal;font-family: Verdana\">De igual manera, la Alcaldesa presenci&oacute; la labor del personal del Gobierno de Hermosillo que conforma las Brigadas de Vida, que en dicho punto aplican pruebas r&aacute;pidas y gratuitas de Covid-19 a quienes as&iacute; lo soliciten. Tambi&eacute;n se toma la temperatura a los automovilistas y se informa sobre prevenci&oacute;n del virus.<\/p>\n<p style=\"font-size: 14px;line-height: normal;font-family: Verdana;min-height: 17px\">&nbsp;<\/p>\n<p style=\"font-size: 14px;line-height: normal;font-family: Verdana\">Bernardeth Ruiz, directora de DIF Hermosillo, apunt&oacute; que tanto en el m&oacute;dulo de Brigadas de Vida como en las jornadas de salud en el &aacute;rea rural del Municipio, se han realizado m&aacute;s de 600 pruebas r&aacute;pidas, de las cuales un 20% han tenido en su sistema inmunol&oacute;gico la presencia de Covid-19.<\/p>\n<p style=\"font-size: 14px;line-height: normal;font-family: Verdana;min-height: 17px\">&nbsp;<\/p>\n<p style=\"font-size: 14px;line-height: normal;font-family: Verdana\">Destac&oacute; que el Gobierno Municipal se coordina con la Secretar&iacute;a de Salud para atender a los identificados positivos o con riesgo, tanto en el casco urbano como en el &aacute;rea rural, para poderlos canalizar a los Centros Covid o a la instancia m&eacute;dica correspondiente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Supervisa Celida Lopez filtros preventivos en Hermosillo<\/p>\n","protected":false},"author":1,"featured_media":154440,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[10307],"class_list":["post-154439","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-ayto-de-hermosillo"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2020\/07\/1593842836_CLC3JULIO.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/154439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=154439"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/154439\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/154440"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=154439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=154439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=154439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}