{"id":152401,"date":"2020-08-07T00:07:22","date_gmt":"2020-08-07T00:07:22","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2020\/08\/07\/por-que-el-home-tiene-forma-de-pentagono\/"},"modified":"2020-08-07T00:07:22","modified_gmt":"2020-08-07T00:07:22","slug":"por-que-el-home-tiene-forma-de-pentagono","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2020\/08\/07\/por-que-el-home-tiene-forma-de-pentagono\/","title":{"rendered":"Por que el home tiene forma de pentagono?"},"content":{"rendered":"<p>El home o home plate es&nbsp;<strong style=\"margin: 0px;padding: 0px\">el lugar en el que se centra la mayor parte de la emoci&oacute;n del beisbol<\/strong>, donde se anota la carrera del triunfo o en donde se consigue el out con un ponche. Ese punto del campo es tambi&eacute;n una base pero que es diferente a las otras tres, y aqu&iacute; viene la pregunta:&nbsp;<strong style=\"margin: 0px;padding: 0px\">&iquest;por qu&eacute; el home es un pent&aacute;gono?<\/strong><\/p>\n<p>La forma que tiene el home actualmente se obtuvo&nbsp;<strong style=\"margin: 0px;padding: 0px\">despu&eacute;s de pasar por dos etapas previas<\/strong>, llegando a la que conocemos a partir del a&ntilde;o 1901. A continuaci&oacute;n te explicamos las formas que tuvo:<\/p>\n<div id=\"outstream_article\" data-id=\"115\" data-m=\"{&quot;i&quot;:115,&quot;p&quot;:113,&quot;n&quot;:&quot;article-inlineOutstreamAd&quot;,&quot;t&quot;:&quot;inlineOutstreamAd&quot;,&quot;o&quot;:2}\">&nbsp;<\/div>\n<h1><strong style=\"margin: 0px;padding: 0px\">LOS INICIOS<\/strong><\/h1>\n<p>En los primeros a&ntilde;os del beisbol (a finales de los a&ntilde;os 1800),&nbsp;<strong style=\"margin: 0px;padding: 0px\">el home no ten&iacute;a una forma oficial&nbsp;<\/strong>pero su presentaci&oacute;n b&aacute;sicamente eran objetos redondos hechos de distintos materiales. Algunos de estos fueron platos o discos, lo que se cree&nbsp;<strong style=\"margin: 0px;padding: 0px\">llev&oacute; a que se le diera el nombre de &#8220;home plate&#8221;<\/strong>, o como tambi&eacute;n se le conoce actualmente, &#8220;el plato&#8221;.&nbsp;<\/p>\n<h1><strong style=\"margin: 0px;padding: 0px\">EL PRIMER CAMBIO: CUADRADO<\/strong><\/h1>\n<p>Al llegar al a&ntilde;o 1900, en las reglas se estableci&oacute; que&nbsp;<strong style=\"margin: 0px;padding: 0px\">el home deb&iacute;a de tener la misma forma del resto de las bases<\/strong>, por lo que se hicieron cuadradas, con una medida de 12 pulgadas por lado. El home se acomod&oacute; con uno de los v&eacute;rtices apuntando al pitcher y el otro al catcher. Estas bases estaban hechas de piedra o de m&aacute;rmol. La posici&oacute;n que ten&iacute;a el home y el material del que estaba hecho hizo que la esquina del lado de tercera base provocara lesiones a los jugadores que se barr&iacute;an (normalmente se cortaban).&nbsp;<\/p>\n<h1><strong style=\"margin: 0px;padding: 0px\">EL HOME EN FORMA DE PENT&Aacute;GONO<\/strong><\/h1>\n<p>Lo peligroso que result&oacute; tener un home en forma cuadrada llev&oacute; a la creaci&oacute;n del pent&aacute;gono. En 1901,&nbsp;<strong style=\"margin: 0px;padding: 0px\">Robert Keating cre&oacute; el home plate de cinco lados<\/strong>. El acomodo se decidi&oacute; porque los dos lados que est&aacute;n hacia el catcher, apuntan directamente a la l&iacute;nea de tercera y primera base, y porque&nbsp;<strong style=\"margin: 0px;padding: 0px\">esa posici&oacute;n permiti&oacute; que la zona de strike fuera m&aacute;s visible tanto para el pitcher como para el umpire<\/strong>, lo que permiti&oacute; mayor consistencia a las llamadas del ampayer.&nbsp;<\/p>\n<p>Estas razones son las que provocaron el cambio de un objeto redondo a un cuadrado a un pent&aacute;gono, teniendo como l&oacute;gica principal,&nbsp;<strong style=\"margin: 0px;padding: 0px\">que el home deb&iacute;a de tener una forma diferente porque su prop&oacute;sito dentro del juego es distinto<\/strong>&nbsp;al de las otras bases, especialmente para determinar la zona de strike.<strong style=\"margin: 0px;padding: 0px\">&nbsp;S&eacute;ptima Entrada<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por que el home tiene forma de pentagono?<\/p>\n","protected":false},"author":1,"featured_media":152402,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[336],"tags":[104],"class_list":["post-152401","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-mlb"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2020\/08\/1596784042_WhatsApp-Image-2019-10-08-at-3.11.25-PM.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/152401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=152401"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/152401\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/152402"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=152401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=152401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=152401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}