{"id":151885,"date":"2020-08-17T14:08:43","date_gmt":"2020-08-17T14:08:43","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2020\/08\/17\/la-comida-chatarra-se-debe-disuadir-primero-desde-los-hogares-canacope-hmo\/"},"modified":"2020-08-17T14:08:43","modified_gmt":"2020-08-17T14:08:43","slug":"la-comida-chatarra-se-debe-disuadir-primero-desde-los-hogares-canacope-hmo","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2020\/08\/17\/la-comida-chatarra-se-debe-disuadir-primero-desde-los-hogares-canacope-hmo\/","title":{"rendered":"La comida chatarra se debe disuadir primero desde los hogares: Canacope HMO"},"content":{"rendered":"<p class=\"MsoNormal\"><span>La C&aacute;mara Nacional de Comercio, Servicios y Turismo en Peque&ntilde;o de Hermosillo (Canacope Servytur), considera que toda medida o ley encaminada en mejorar la salud en especial de la ni&ntilde;ez mexicana debe ser buena, pero no si en su paso se afecta a sectores econ&oacute;micos, que en este caso ser&iacute;an los micro empresarios.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Martin Zalazar Zazueta, Presidente en Hermosillo de la Canacope, dio a conocer que como sector econ&oacute;mico, comprenden a la perfecci&oacute;n el tema de las restricciones a la comida chatarra hacia los menores de edad, pero de la misma forma hay un reconocimiento claro, que para alcanzar ese objetivo por parte de las autoridades federales y estatales, se afectar&iacute;a gravemente a un apartado del sector econ&oacute;mico que vende ese tipo de productos.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&ldquo;En Canacope Hermosillo estamos de acuerdo con el re etiquetado en los productos considerados como comida chatarra, mas no la prohibici&oacute;n de ellos. Esto es porque en t&eacute;rminos de la econom&iacute;a de empresas, afectar&iacute;a a los micro empresarios, a los changarros, abarrotes que sobreviven muchos de ellos por la venta de estos productos e igual es una situaci&oacute;n que habr&aacute;n de padecer muchos negocios m&aacute;s&rdquo;, dijo.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Abund&oacute;, que sin duda los problemas de salud en M&eacute;xico asociados al sobre peso, obesidad, diabetes y dem&aacute;s enfermedades cr&oacute;nico degenerativas son reales, pero la verdadera soluci&oacute;n a cambiar todo eso, est&aacute; primero en realizar un cambio cultural a trav&eacute;s de la educaci&oacute;n y la actividad f&iacute;sica.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Resalt&oacute;, que lo que acaba de aprobarse en el estado de Oaxaca, donde su congreso estableci&oacute; la prohibici&oacute;n de la venta de alimentos y bebidas no alcoh&oacute;licas pre envasados a ni&ntilde;os, representa un avance, una buena intenci&oacute;n, pero detr&aacute;s de ello, queda un gran hueco, porque esas medidas no representan la soluci&oacute;n para una a&ntilde;eja problem&aacute;tica en la salud de los mexicanos.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&ldquo;Como empresarios estamos a favor que M&eacute;xico viva en las mejores condiciones posibles, pero si en este caso se atentar&aacute; contra una parte del sector comercio, no lo apoyamos. Nuestros legisladores y dem&aacute;s autoridades, deben de entender que en estos tiempos donde se vive una nueva situaci&oacute;n dif&iacute;cil por el coronavirus, donde la econom&iacute;a se cay&oacute; y con muchos esfuerzos se busca recuperar, es que necesitamos soluciones y no malas noticias que en este caso en particular le pegar&aacute; directo a muchos micro empresarios&rdquo;, cont&oacute;.<span>&nbsp; <\/span><\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>A&ntilde;adi&oacute;, que ese tipo de leyes prohibitivas no solo atentan contra los due&ntilde;os de establecimientos comerciales que venden productos que se buscan prohibir a menores de edad, sino que la cadena se pasa a miles de familias y de empleos que se generan en cada uno de los municipios de este pa&iacute;s.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&ldquo;Pensemos como mexicanos y todos juntos, en soluciones donde nadie resulte perjudicado. La llegada del Covid-19 nos ha dejado el que vivamos en una nueva realidad, entonces aprovechemos ello para que de nuestras casas comencemos a cambiar la cultura de no consumir alimentos considerados chatarra. Si se logra eso primero, estamos seguros que las afectaciones al sector comercio ser&aacute;n m&iacute;nimas e incluso nos har&aacute; tambi&eacute;n adaptarnos a nuevas normas de consumo pero sin generar caos&rdquo;, concluy&oacute;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La comida chatarra se debe disuadir primero desde los hogares: Canacope Hermosillo<\/p>\n","protected":false},"author":1,"featured_media":151886,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[8798],"class_list":["post-151885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-canacope-hermosillo"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2020\/08\/1597698523_tiendas_de_abarrotes_-250.jpg_554688468.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/151885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=151885"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/151885\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/151886"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=151885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=151885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=151885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}