{"id":151673,"date":"2020-08-21T13:23:57","date_gmt":"2020-08-21T13:23:57","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2020\/08\/21\/designa-ine-a-benjamin-hernandez-avalos-como-consejero-electoral-en-sonora\/"},"modified":"2020-08-21T13:23:57","modified_gmt":"2020-08-21T13:23:57","slug":"designa-ine-a-benjamin-hernandez-avalos-como-consejero-electoral-en-sonora","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2020\/08\/21\/designa-ine-a-benjamin-hernandez-avalos-como-consejero-electoral-en-sonora\/","title":{"rendered":"Designa INE a Benjamin Hernandez Avalos como Consejero Electoral en Sonora"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">Hermosillo, Sonora. Agosto 21,2020.- El Consejo General del IEE Sonora da &nbsp;la bienvenida al Maestro Benjam&iacute;n Hern&aacute;ndez Avalos designado por el Consejo General del Instituto Nacional Electoral (INE) como Consejero Electoral de Sonora, en sesi&oacute;n p&uacute;blica celebrada este d&iacute;a.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">La Consejera Presidenta Guadalupe Taddei Zavala celebr&oacute; la designaci&oacute;n y record&oacute; que est&aacute; en marcha el arranque del Proceso Electoral Local Ordinario 2020-2021, trabajos a los que se sumar&aacute; el nuevo consejero electoral de este Instituto.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">Taddei Zavala &nbsp;destac&oacute; el trabajo que realiz&oacute; el INE a trav&eacute;s de convocatorias p&uacute;blicas en diez entidades de la rep&uacute;blica, para la integraci&oacute;n de los &oacute;rganos de direcci&oacute;n de los Organismos P&uacute;blicos Locales.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">En la sesi&oacute;n de este d&iacute;a, el INE design&oacute; consejeras y consejeros electorales para los Organismos P&uacute;blicos Locales de Campeche, Chiapas, Michoac&aacute;n, Morelos, Nuevo Le&oacute;n, San Luis Potos&iacute; y Sonora adem&aacute;s de la designaci&oacute;n del Consejero Presidente en los Oples de Durango, &nbsp;Michoac&aacute;n y Nayarit; quienes permanecer&aacute;n en su cargo por un per&iacute;odo de siete a&ntilde;os.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Designa INE a Benjamin Hernandez Avalos como Consejero Electoral en Sonora<\/p>\n","protected":false},"author":1,"featured_media":151674,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[2203],"class_list":["post-151673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-iee"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2020\/08\/1598041437_CBenjamin.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/151673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=151673"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/151673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/151674"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=151673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=151673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=151673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}