{"id":151385,"date":"2020-08-26T16:53:58","date_gmt":"2020-08-26T16:53:58","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2020\/08\/26\/inicia-en-sonora-la-primera-feria-virtual-de-empleo\/"},"modified":"2020-08-26T16:53:58","modified_gmt":"2020-08-26T16:53:58","slug":"inicia-en-sonora-la-primera-feria-virtual-de-empleo","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2020\/08\/26\/inicia-en-sonora-la-primera-feria-virtual-de-empleo\/","title":{"rendered":"Inicia en Sonora la primera feria virtual de empleo"},"content":{"rendered":"<p class=\"MsoNormal\"><span>A partir de este mi&eacute;rcoles 26 de agosto la Secretaria del Trabajo en Sonora y el Servicio Nacional del Empleo, coordinan la primera Feria del Empleo Virtual y donde 10 empresas en la localidad ofrecen m&aacute;s de 200 vacantes.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Horacio Valenzuela Ibarra, Secretario del Trabajo en Sonora, agradeci&oacute; a todas las empresas participantes para formar parte de esa primera feria de empleo virtual en la entidad y porque con su respaldo se contribuye para la reactivaci&oacute;n econ&oacute;mica en la entidad.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&ldquo;Esta primera feria de empleo virtual en Sonora ser&aacute; de gran ayuda para ir generando esa reactivaci&oacute;n en la econom&iacute;a, la cual se ha visto sumamente afectada por la pandemia de Covid-19. Por eso, reiteramos el agradecimiento a empresas como Zobele, S&uacute;per del Norte, City Club, Rancho el 17, Coppel, Grupo Alta y otras m&aacute;s por creer en el estado y por sumarse a la generaci&oacute;n de nuevas fuentes de empleo&rdquo;, detall&oacute;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span>&nbsp;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>Para los interesados en buscar un empleo en alguna de esas empresas en la entidad, manifest&oacute; que deben enviar su curr&iacute;culo vitae al correo: <a href=\"mailto:feriasdeempleo.snesonora@gmail.com\">feriasdeempleo.snesonora@gmail.com<\/a> y ah&iacute; cada una de las empresas analizar&aacute;n cada uno de los perfiles para los puestos vacantes.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Finalmente Donacio Dom&iacute;nguez Espinoza, Subcoordinador del Servicio Nacional del Empleo a nivel federal, reconoci&oacute; la gesti&oacute;n que realiza el Estado de Sonora para buscar reactivar su econom&iacute;a y generar mayores fuentes de empleo en empresas formales.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&ldquo;Reconocemos que en Sonora se ha estado haciendo un buen trabajo por buscar recuperar parte de su actividad econ&oacute;mica al igual que en otros estados del pa&iacute;s. Nos toc&oacute; vivir una circunstancia muy dif&iacute;cil por el Covid-19 y por eso queremos recuperar los empleos formales de la mano con empresas que nos ayuden a superar esta crisis&rdquo;, concluy&oacute;.<\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Inicia en Sonora la primera feria virtual de empleo <\/p>\n","protected":false},"author":1,"featured_media":151386,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[255],"class_list":["post-151385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-sne"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2020\/08\/1598486038_touch.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/151385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=151385"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/151385\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/151386"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=151385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=151385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=151385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}