{"id":149634,"date":"2020-09-29T14:56:16","date_gmt":"2020-09-29T14:56:16","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2020\/09\/29\/frente-frio-ayudara-a-bajar-un-poco-las-temperaturas-en-sonora-conagua-2\/"},"modified":"2020-09-29T14:56:16","modified_gmt":"2020-09-29T14:56:16","slug":"frente-frio-ayudara-a-bajar-un-poco-las-temperaturas-en-sonora-conagua-2","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2020\/09\/29\/frente-frio-ayudara-a-bajar-un-poco-las-temperaturas-en-sonora-conagua-2\/","title":{"rendered":"Frente frio ayudara a bajar un poco las temperaturas en Sonora: Conagua"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>Desde este martes en Sonora, se comenzaron a sentir efectos indirectos del frente fr&iacute;o n&uacute;mero 4 de la temporada y lo cual ayudar&aacute; para bajar un poco los valores m&aacute;ximos en especial, resalt&oacute; Gilberto Lagarda V&aacute;zquez.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>El meteor&oacute;logo de la Comisi&oacute;n Nacional del Agua en Sonora (Conagua), dijo que ese nuevo fen&oacute;meno meteorol&oacute;gico no entrar&aacute; a la entidad, pero s&iacute; dejar&aacute; algunos efectos indirectos desde este martes en especial en la franja que colinda con el estado de Chihuahua.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><strong><span>&nbsp;&ldquo;Ocasionar&aacute; para la entidad algunas rachas de vientos que andar&aacute;n en alrededor de los 40 kil&oacute;metros por hora en forma intermitente y adem&aacute;s se espera que genere un ligero descenso de las temperaturas pero solo en el noreste y oriente del estado, es decir, municipios que colindan con chihuahua son los que podr&iacute;an ser beneficiados con este descenso de temperaturas. Ya para los siguientes d&iacute;as el descenso que se espera sea ligero nada m&aacute;s, podr&iacute;a ya sentirse en todo el estado a partir de este mi&eacute;rcoles&rdquo;, afirm&oacute;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>Detall&oacute;, que los efectos indirectos de ese cuarto frente fr&iacute;o de la temporada, ayudar&aacute; para que los municipios m&aacute;s calurosos en la entidad como San Luis R&iacute;o Colorado, Hermosillo, Cajeme y Navojoa, promedien en los pr&oacute;ximos d&iacute;as valores en alrededor de los 40 grados cent&iacute;grados.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frente frio ayudara a bajar un poco las temperaturas en Sonora: Conagua<\/p>\n","protected":false},"author":1,"featured_media":149635,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[224],"class_list":["post-149634","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-conagua"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2020\/09\/1601416576_frentefrio32.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/149634","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=149634"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/149634\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/149635"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=149634"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=149634"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=149634"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}