{"id":149405,"date":"2020-10-02T15:02:32","date_gmt":"2020-10-02T15:02:32","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2020\/10\/02\/mujer-que-dejo-de-fumar-gracias-a-la-hipnosis-y-construyo-un-imperio-millonario\/"},"modified":"2020-10-02T15:02:32","modified_gmt":"2020-10-02T15:02:32","slug":"mujer-que-dejo-de-fumar-gracias-a-la-hipnosis-y-construyo-un-imperio-millonario","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2020\/10\/02\/mujer-que-dejo-de-fumar-gracias-a-la-hipnosis-y-construyo-un-imperio-millonario\/","title":{"rendered":"Mujer que dejo de fumar gracias a la hipnosis y construyo un imperio millonario"},"content":{"rendered":"<p>La serie semanal The Boss de la BBC presenta perfiles de diferentes l&iacute;deres empresariales de todo el mundo. Esta semana hablamos con la hipnotista estadounidense Grace Smith, quien cre&oacute; un imperio a partir de una experiencia personal.<\/p>\n<p>Grace Smith pudo dejar el alcohol, pero dejar de fumar le parec&iacute;a imposible.<\/p>\n<p>En 2011, a sus 25 a&ntilde;os, ten&iacute;a un estresante trabajo recaudando fondos en Nueva York.<\/p>\n<p>&#8220;No ten&iacute;a ning&uacute;n mecanismo saludable para sobrellevar la situaci&oacute;n&#8221;, recuerda.<\/p>\n<p>&#8220;Ir de fiesta era una de las maneras que utilizaba para&nbsp;<strong style=\"margin: 0px;padding: 0px\">lidiar<\/strong><strong style=\"margin: 0px;padding: 0px\">&nbsp;con todo el estr&eacute;s<\/strong>&nbsp;y la ansiedad&#8221;.&#8221;Viv&iacute;a en el Lower East Side, y eso era lo que todos mis amigos hac&iacute;an tambi&eacute;n: trabaj&aacute;bamos muy duro todo el d&iacute;a y festejamos muy duro toda la noche. Me cost&oacute; mucho, f&iacute;sica y mentalmente&#8221;.<\/p>\n<p>Grace se dio cuenta de que necesitaba llevar una vida m&aacute;s sana, as&iacute; que dej&oacute; de salir de fiesta y decidi&oacute; abandonar el alcohol.<\/p>\n<p>Pero&nbsp;<strong style=\"margin: 0px;padding: 0px\">no&nbsp;<\/strong><strong style=\"margin: 0px;padding: 0px\">lograba&nbsp;<\/strong><strong style=\"margin: 0px;padding: 0px\">dejar de fumar<\/strong>, incluso despu&eacute;s de probar chicles y parches, y hasta tratar de abandonar el vicio repentinamente.<\/p>\n<h3>Una sola sesi&oacute;n bast&oacute;<\/h3>\n<p>Finalmente, una amiga le sugiri&oacute; que probara la hipnosis.<\/p>\n<p>&#8220;Estaba muy esc&eacute;ptica&#8221;, dice Grace. &#8220;No sab&iacute;a si ser&iacute;a un vaiv&eacute;n&#8230; o&nbsp;<strong style=\"margin: 0px;padding: 0px\">simplemente un enga&ntilde;o<\/strong>&#8220;.<\/p>\n<p>Pero ahora asegura que logr&oacute; dejar la nicotina despu&eacute;s de una sola sesi&oacute;n. Y la experiencia la inspir&oacute; a convertirse ella misma en hipnoterapeuta.<\/p>\n<p>Hoy, Grace dirige su negocio&nbsp;<strong style=\"margin: 0px;padding: 0px\">Grace Space Hypnosis<\/strong><strong style=\"margin: 0px;padding: 0px\">,&nbsp;<\/strong>el cual ofrece sesiones de hipnoterapia en l&iacute;nea a m&aacute;s de 250.000 personas en todo el mundo, incluyendo a jefes de empresas de la lista Fortune 500, atletas y celebridades.<\/p>\n<p>Esta empresaria de 34 a&ntilde;os tambi&eacute;n aparece con cierta frecuencia en la televisi&oacute;n estadounidense y es autora de dos libros de hipnosis.<\/p>\n<p>Pero, &iquest;qu&eacute; es exactamente la hipnoterapia?<\/p>\n<h3>Para perder peso, desestresarse o dejar un h&aacute;bito<\/h3>\n<p>El Oxford English Dictionary define el hipnotismo como &#8220;causar de manera artificial un estado en el que el sujeto parece estar en un sue&ntilde;o profundo, sin ning&uacute;n poder de cambiar su condici&oacute;n mental o f&iacute;sica, excepto bajo la influencia de alguna&nbsp;<strong style=\"margin: 0px;padding: 0px\">sugerencia&nbsp;<\/strong><strong style=\"margin: 0px;padding: 0px\">u orden&nbsp;<\/strong><strong style=\"margin: 0px;padding: 0px\">externa<\/strong>, a la que obedece involuntaria e inconscientemente&#8221;.<\/p>\n<p>Grace lo define simplemente como &#8220;meditaci&oacute;n con un objetivo&#8221;.<\/p>\n<p>Sus clientes la utilizan para alcanzar una&nbsp;<strong style=\"margin: 0px;padding: 0px\">gran variedad de objetivos<\/strong>, desde perder peso, dejar un h&aacute;bito, desestresarse y hasta para conseguir una ambici&oacute;n.<\/p>\n<p>Si bien algunas personas todav&iacute;a consideran la hipnoterapia como una pr&aacute;ctica controvertida, su empleo cuenta con el apoyo de muchas organizaciones m&eacute;dicas.<\/p>\n<p>Por ejemplo, la Cancer Research UK asegura que &#8220;algunas personas con c&aacute;ncer utilizan la hipnoterapia&nbsp;<strong style=\"margin: 0px;padding: 0px\">para relajarse<\/strong>&nbsp;y afrontar los s&iacute;ntomas y el tratamiento&#8221;.<\/p>\n<p>Nacida y criada en Nueva Jersey, Grace obtuvo una licenciatura combinada en Ingl&eacute;s, Administraci&oacute;n de Empresas y Estudios Religiosos en el Wagner College de Nueva York. Luego hizo una maestr&iacute;a en Estudios de Derechos Humanos en la Universidad de Columbia.<\/p>\n<p>Para convertirse en hipnoterapeuta en 2011, complet&oacute; un curso de certificaci&oacute;n de 250 horas mientras trabajaba a tiempo completo. Es el tipo de capacitaci&oacute;n que se requiere en Estados Unidos, pero var&iacute;a mucho de un pa&iacute;s a otro.<\/p>\n<h3>Sesiones a trav&eacute;s de videollamadas<\/h3>\n<p>Despu&eacute;s de que Grace termin&oacute; el curso, dej&oacute; su trabajo recaudando fondos y se convirti&oacute; en una&nbsp;<strong style=\"margin: 0px;padding: 0px\">hipnoterapeuta profesional<\/strong>&nbsp;en una oficina &#8220;diminuta&#8221; en Nueva York.<\/p>\n<p>Para atraer a sus primeros clientes, anunci&oacute; un precio de oferta inicial en LivingSocial, un sitio especializado en comercio online que ahora forma parte de Groupon.<\/p>\n<p>Logr&oacute; vender 952 sesiones en 24 horas, y luego vinieron m&aacute;s personas gracias&nbsp;<strong style=\"margin: 0px;padding: 0px\">al boca a boca positivo<\/strong>.<\/p>\n<p>Las sesiones iniciales fueron cara a cara, pero luego Grace traslad&oacute; su negocio a internet y las sesiones se hac&iacute;an a trav&eacute;s de videollamadas.<\/p>\n<ul>\n<li style=\"margin: 0px 0px 1.9rem;padding: 0px\"><a style=\"margin: 0px;padding: 0px;color: #126d91\" href=\"https:\/\/www.bbc.com\/mundo\/noticias-46061786?xtor=AL-73-%5Bpartner%5D-%5Bmicrosoft%5D-%5Blink%5D-%5Bmundo%5D-%5Bbizdev%5D-%5Bisapi%5D\" target=\"_blank\" data-id=\"104\" data-m=\"{&quot;i&quot;:104,&quot;p&quot;:95,&quot;n&quot;:&quot;partnerLink&quot;,&quot;y&quot;:24,&quot;o&quot;:9}\" rel=\"noopener\">C&oacute;mo me convert&iacute; en mi propio jefe a los 20 a&ntilde;os<\/a><\/li>\n<\/ul>\n<p>Ella dice que la idea la tom&oacute; de sus clientes en el mundo corporativo, que&nbsp;<strong style=\"margin: 0px;padding: 0px\">quer&iacute;an&nbsp;<\/strong><strong style=\"margin: 0px;padding: 0px\">seguir con&nbsp;<\/strong><strong style=\"margin: 0px;padding: 0px\">sus sesiones<\/strong>&nbsp;mientras estaban realizando viajes de negocios.<\/p>\n<p>Despu&eacute;s de dos a&ntilde;os, su esposo brasile&ntilde;o, Bernardo Feitosa, se incorpor&oacute; al negocio para manejar el lado tecnol&oacute;gico de la empresa.<\/p>\n<p>En los &uacute;ltimos a&ntilde;os, el inter&eacute;s en Grace y su negocio -que ahora tiene su sede en Florida- ha crecido fuertemente, gracias en gran parte a sus apariciones en la televisi&oacute;n.<\/p>\n<p>Ha estado en programas que tratan temas de salud como el de The Doctors de CBS y el The Dr Oz Show de Sony.<\/p>\n<p>Jodi Clarke, fundadora de la empresa australiana de hipnoterapia Awaecnan, dice que Grace ha trabajado &#8220;incansablemente para que la hipnosis se vuelva&nbsp;<em style=\"margin: 0px;padding: 0px\">mainstream<\/em>&#8220;.<\/p>\n<h3>&#8220;Todav&iacute;a la gente no lo entiende bien&#8221;<\/h3>\n<p>Mientras tanto, el psic&oacute;logo brit&aacute;nico Jamie Hacker Hughes afirma que Grace y otros hipnoterapeutas como ella &#8220;pueden ser muy efectivos a la hora de ayudar a pacientes a&nbsp;<strong style=\"margin: 0px;padding: 0px\">manejar una amplia gama de&nbsp;<\/strong><strong style=\"margin: 0px;padding: 0px\">situaciones<\/strong>&#8220;, y pueden emplear la hipnoterapia &#8220;como un complemento de la terapia utilizada en psicolog&iacute;a, medicina y odontolog&iacute;a. &#8220;.<\/p>\n<p>Para ayudar a capacitar y certificar a m&aacute;s hipnoterapeutas, en 2016 Grace abri&oacute; su propia escuela, que est&aacute; aprobada tanto por la Asociaci&oacute;n Internacional de Consejeros y Terapeutas (IACT, por sus siglas en ingl&eacute;s) como por la International Hypnosis Federation.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La mujer que dejo de fumar gracias a la hipnosis y construyo un imperio millonario de hipnoterapia<\/p>\n","protected":false},"author":1,"featured_media":149406,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[336],"tags":[10081],"class_list":["post-149405","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-curiosidades","tag-hipnosis"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2020\/10\/1601676152_3420291w960.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/149405","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=149405"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/149405\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/149406"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=149405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=149405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=149405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}