{"id":148118,"date":"2020-10-28T15:05:39","date_gmt":"2020-10-28T15:05:39","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2020\/10\/28\/lista-canacope-hermosillo-para-participar-en-el-buen-fin-2020\/"},"modified":"2020-10-28T15:05:39","modified_gmt":"2020-10-28T15:05:39","slug":"lista-canacope-hermosillo-para-participar-en-el-buen-fin-2020","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2020\/10\/28\/lista-canacope-hermosillo-para-participar-en-el-buen-fin-2020\/","title":{"rendered":"Lista Canacope Hermosillo para participar en el Buen Fin 2020"},"content":{"rendered":"<p class=\"MsoNormal\"><span>Se declara lista la Canacope en Hermosillo para participar y sumarse al programa del Buen Fin 2020, y el cual ahora se va a desarrollar en todo el pa&iacute;s, del 9 al 20 de noviembre pr&oacute;ximo.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Martin Zalazar Zazueta, Presidente de la C&aacute;mara Nacional de Comercio, Servicios y Turismo en Peque&ntilde;o de Hermosillo (Canacope Servytur), indic&oacute; que nueva cuenta gracias al esfuerzo de autoridades gubernamentales, empresarios y sociedad civil, se podr&aacute; realizar la d&eacute;cima edici&oacute;n de ese programa, que ahora por motivo de la pandemia va de privilegiar el tema de la salud y alargar&aacute; durante 12 d&iacute;as la duraci&oacute;n del mismo.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&ldquo;Canacope Hermosillo forma parte de los organismos empresariales de Sonora que estamos participando en esta actividad nacional, la cual es de las m&aacute;s importantes en el a&ntilde;o por la gran cantidad de ventas y de econom&iacute;a local genera. Por eso para este 2020 y a&uacute;n con la pandemia presente, estamos seguros que al finalizar con este programa vamos a lograr entre todos las metas que nos planteamos y ayudar a la recuperaci&oacute;n econ&oacute;mica que tan falta nos hace&rdquo;, dijo.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><strong><span>&nbsp;<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>Agreg&oacute;, que la derrama econ&oacute;mica que se espera genere el Buen Fin 2020 en Sonora, sea no menor a los 955 millones de pesos que se registraron en el 2019 y por eso alent&oacute; a empresas de todos los giros que a&uacute;n no se inscriben a ese programa, a que lo hagan a trav&eacute;s de la p&aacute;gina <span class=\"MsoHyperlink\"><a href=\"http:\/\/www.elbuenfin.concanaco.com.mx\/\">www.elbuenfin.concanaco.com.mx<\/a><\/span>, ya que ahora habr&aacute; beneficios tanto para consumidores como para los negocios participantes con sorteos especiales.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Finalmente el presidente de la Canacope Hermosillo mencion&oacute; que, este Buen Fin 2020 contendr&aacute; de nuevas cuenta muchas ofertas, descuentos y un sinf&iacute;n de rebajas significativas en miles de productos y servicios que estar&aacute;n al alcance de millones de personas.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&ldquo;Tenemos mucha confianza que este Buen Fin 2020 sea un gran oxigeno e impulso para la econom&iacute;a local que se ha visto muy afectada por la pandemia. Sabemos que este a&ntilde;o el comercio electr&oacute;nico habr&aacute; de crecer mucho m&aacute;s as&iacute; como el uso de tarjetas de cr&eacute;dito y d&eacute;bito para realizar sus compras&rdquo;, culmin&oacute;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lista Canacope Hermosillo para participar en el Buen Fin 2020 <\/p>\n","protected":false},"author":1,"featured_media":148119,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[8798],"class_list":["post-148118","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-canacope-hermosillo"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2020\/10\/1603922739_buen-fin-digital.png","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/148118","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=148118"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/148118\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/148119"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=148118"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=148118"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=148118"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}