{"id":142316,"date":"2021-02-20T11:27:59","date_gmt":"2021-02-20T11:27:59","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2021\/02\/20\/rescata-gobierno-de-celida-lopez-avenida-tamaulipas-en-la-5-de-mayo\/"},"modified":"2021-02-20T11:27:59","modified_gmt":"2021-02-20T11:27:59","slug":"rescata-gobierno-de-celida-lopez-avenida-tamaulipas-en-la-5-de-mayo","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2021\/02\/20\/rescata-gobierno-de-celida-lopez-avenida-tamaulipas-en-la-5-de-mayo\/","title":{"rendered":"Rescata gobierno de Celida Lopez avenida Tamaulipas en la 5 de mayo"},"content":{"rendered":"<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\"><strong>Hermosillo, Sonora; febrero 20 de 2021.-<\/strong>&nbsp;La Alcaldesa Celida L&oacute;pez C&aacute;rdenas supervis&oacute; el rescate de la avenida Tamaulipas, en la colonia 5 de mayo, en cuya renovaci&oacute;n integral se invirtieron cerca de 3 millones de pesos del aporte extraordinario que envi&oacute; a Hermosillo el Gobierno Federal encabezado por el Presidente Andr&eacute;s Manuel L&oacute;pez Obrador a trav&eacute;s de SEDATU.<\/p>\n<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">&nbsp;<\/p>\n<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">La vialidad se rehabilit&oacute; por completo entre las calles Revoluci&oacute;n y 5 de Febrero, y la obra incluy&oacute; la nivelaci&oacute;n de 2 pozos de visita y 2 cajas de v&aacute;lvulas, como paso previo al bacheo en 365.17 metros de la calle y el recarpeteo de 7 mil 449 metros cuadrados con carpeta asf&aacute;ltica, donde ya est&aacute; lista la se&ntilde;alizaci&oacute;n vial con pintura.<\/p>\n<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">&nbsp;<\/p>\n<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Acompa&ntilde;ada de vecinos del sector y el titular de CIDUE, Jos&eacute; Carillo Atondo, la Presidenta Municipal supervis&oacute; tambi&eacute;n la construcci&oacute;n de 595 metros cuadrados de banquetas y 30 metros cuadrados de rampas, as&iacute; como la colocaci&oacute;n de mobiliario urbano consistente en 6 botes para basura y 6 bancas.&nbsp;<\/p>\n<div>&nbsp;<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rescata gobierno de Celida Lopez avenida Tamaulipas en la 5 de mayo<\/p>\n","protected":false},"author":1,"featured_media":142317,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[7078],"class_list":["post-142316","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-ayto-hermosillo"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2021\/02\/1613845679_CLCTAMAULIPAS2.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/142316","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=142316"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/142316\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/142317"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=142316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=142316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=142316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}