{"id":141483,"date":"2021-03-05T20:42:25","date_gmt":"2021-03-05T20:42:25","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2021\/03\/05\/un-sonora-ganadora-la-propuesta-de-ernesto-gandara\/"},"modified":"2021-03-05T20:42:25","modified_gmt":"2021-03-05T20:42:25","slug":"un-sonora-ganadora-la-propuesta-de-ernesto-gandara","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2021\/03\/05\/un-sonora-ganadora-la-propuesta-de-ernesto-gandara\/","title":{"rendered":"Un Sonora Ganadora, la propuesta de Ernesto Gandara"},"content":{"rendered":"<p><span>Una campa&ntilde;a innovadora, creativa y cargada de propuestas es lo que present&oacute; Ernesto G&aacute;ndara Camou al inicio del proceso electoral para elegir al futuro gobernador de Sonora.<\/span><\/p>\n<p><span><br \/><\/span><\/p>\n<p><span>Con su concepto &ldquo;Sonora Ganadora&rdquo; manda un mensaje a las familias sonorenses de que a pesar de las crisis de salud y econ&oacute;mica, podemos avanzar si trabajamos unidos, si capitalizamos las oportunidades que se asoman al horizonte y con&nbsp; la fortaleza, la reciedumbre y&nbsp; el car&aacute;cter de Sonora, sumando a ello el liderazgo de G&aacute;ndara Camou, con el tim&oacute;n del barco, nos pondr&aacute;n en la ruta de la esperanza y aunque el mar sea tempestuoso llegaremos a buen puerto.<\/span><\/p>\n<p><span><br \/><\/span><\/p>\n<p><span>La pandemia nos hizo perder mucho: el confinamiento nos aisl&oacute;, el virus nos alej&oacute; del saludo y los abrazos; de las palmadas y los besos. Perdimos el goce de estar juntos, la alegr&iacute;a de reunirnos con quienes amamos. Hoy nos toca ganar. A Sonora le toca ganar. A ti te toca ganar.<\/span><\/p>\n<p><span><br \/><\/span><\/p>\n<p><span>G&aacute;ndara Camou reconoce en su inicio de campa&ntilde;a que nuestro pasado inmediato es de dolor por las muertes de familiares y amigos; de des&aacute;nimo por la p&eacute;rdida de empleos y la afectaci&oacute;n que eso genera a la econom&iacute;a familiar; el &aacute;nimo social esta cargado de pesimismo e incertidumbre, pero justamente de ah&iacute; se desprende esta nueva visi&oacute;n de esperanza, de &aacute;nimo y de trabajo conjunto para vencer de nueva cuenta a la adversidad que pretende pintar un panorama desalentador, pero que al igual que los atardeceres de Sonora, puede convertirse en un acto de sublime trasformaci&oacute;n que nos arrope generosamente.<\/span><\/p>\n<p><span><br \/><\/span><\/p>\n<p><span>Ciertamente la historia est&aacute; escrita &ldquo;en pasado&rdquo;, pero tiene la visi&oacute;n de que nosotros, juntos, la escribiremos en este presente, lleno de retos que nos impulsan a dar lo mejor para Sonora. Si lo hacemos juntos, vamos a salir adelante.<\/span><\/p>\n<p><span><br \/><\/span><\/p>\n<p><span>El Candidato de la Alianza Va Por Sonora nos ha dicho que hemos vivido muchos retos, unos m&aacute;s intensos que otros. Pero siempre con la esperanza de que exista ese futuro pr&oacute;spero que anhelamos para nuestros hijos: lejos de divisiones y en el que las diferencias que existen son salvables con el acuerdo, el respeto y el compromiso de hacer lo mejor para los nuestros.<\/span><\/p>\n<p><span><br \/><\/span><\/p>\n<p><span>&ldquo;El Borrego&rdquo; G&aacute;ndara Camou es sensible a esa situaci&oacute;n, pero a partir de ella es que establece un nuevo camino, indica una forma de salir adelante, no menosprecia el pasado, pero invita a ver el futuro y construirlo juntos, nos llama a verlo y luego concretar esa &ldquo;Sonora Ganadora&rdquo;.<\/span><\/p>\n<p><span><br \/><\/span><\/p>\n<p><span><br \/><\/span><\/p>\n<p><span>Su campa&ntilde;a inicia sustentada en los valores que siempre lo han acompa&ntilde;ado: en la fuerza que le da su familia, con sus esposa e hijas y todos sus hermanos y hermanas; en la trasparencia que lo acompa&ntilde;a en su desempe&ntilde;o p&uacute;blico; en la honestidad con la cual enmarca su carrera y en el respeto a todas las personas, pero particularmente a la mujer.<\/span><\/p>\n<p><span><br \/><\/span><\/p>\n<p><span>La primera sorpresa que nos ofrece su campa&ntilde;a, es el video con el cual se present&oacute; en este su primer contacto como Candidato a la Gubernatura, mediante el cual busca consolidar el respaldo de la ciudadan&iacute;a que lo acompa&ntilde;a desde hace varios a&ntilde;os.<\/span><\/p>\n<p><span><br \/><\/span><\/p>\n<p><span>En esa primera grabaci&oacute;n en video, el Candidato de la Alianza Va Por Sonora patentiza sus valores y pone muy alta la vara para el resto de los aspirantes: de entrada plantea su declaraci&oacute;n 3 de 3, donde incluye declaraci&oacute;n patrimonial, de intereses y ante el SAT; pero adem&aacute;s agrega un examen antidoping, una carta de no antecedentes penales, una carta expedida por autoridad competente donde se establece que a su paso por el gobierno no ha cometido da&ntilde;o patrimonial ni tiene ninguna investigaci&oacute;n ante alg&uacute;n &oacute;rgano de trasparencia o fiscalizaci&oacute;n del gasto gubernamental.<\/span><\/p>\n<p><span><br \/><\/span><\/p>\n<p><span>Y lo m&aacute;s importa presenta una carta de no violencia contra la mujer y establece el compromiso inmediato de promover una ley para que en su gobierno no tengan cabida aquellos con antecedentes de violencia contra mujeres. No es solamente un discurso, es tambi&eacute;n una acci&oacute;n concreta para garantizar su cumplimiento y hacer sentir que &ldquo;Sonora Ganadora&rdquo; es femenina.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un Sonora Ganadora, la propuesta de Ernesto Gandara<\/p>\n","protected":false},"author":1,"featured_media":141484,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[360],"class_list":["post-141483","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-borrego-gandara"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2021\/03\/1615002145_848888707.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/141483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=141483"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/141483\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/141484"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=141483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=141483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=141483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}