{"id":140354,"date":"2021-03-24T14:56:18","date_gmt":"2021-03-24T14:56:18","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2021\/03\/24\/tomara-municipio-de-hermosillo-control-de-la-ptar-alcaldesa\/"},"modified":"2021-03-24T14:56:18","modified_gmt":"2021-03-24T14:56:18","slug":"tomara-municipio-de-hermosillo-control-de-la-ptar-alcaldesa","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2021\/03\/24\/tomara-municipio-de-hermosillo-control-de-la-ptar-alcaldesa\/","title":{"rendered":"Tomara municipio de Hermosillo control de la PTAR: Alcaldesa"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>Es cuesti&oacute;n de d&iacute;as para que el Ayuntamiento de Hermosillo, tenga ya el control total de la operaci&oacute;n de la Planta Tratadora de Aguas Residuales (PTAR), asegur&oacute; C&eacute;lida L&oacute;pez C&aacute;rdenas.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>La alcaldesa de Hermosillo, se&ntilde;al&oacute; que ya se le notific&oacute; a la empresa TIAR Hermosillo, que es quien tiene la concesi&oacute;n de esa planta, el inicio de la cancelaci&oacute;n del contrato de 14 a&ntilde;os restantes con notario p&uacute;blico.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><strong><span>&nbsp;&ldquo;Entonces, a partir de aqu&iacute;, nosotros vamos a tomar el control de la planta tratadora. No hay una demanda judicial, nosotros estamos apeg&aacute;ndose al contrato y el mismo contrato incluye el proceso de cancelaci&oacute;n para este contrato de servicios.&nbsp; Los incumplimientos son absolutamente todos&rdquo;, asegur&oacute;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>A&ntilde;adi&oacute;, que ser&aacute; cuesti&oacute;n de d&iacute;as para tomar el control de esa planta, gracias a que el proceso de cancelaci&oacute;n ya est&aacute; tambi&eacute;n a punto de finiquitarse, a consecuencia de las graves fallas que se encontraron en la operaci&oacute;n de esas instalaciones por la empresa que se contrat&oacute; para ello.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"line-height: 106%\"><span>Finalmente, C&eacute;lida L&oacute;pez, expuso que ese proceso de cancelaci&oacute;n a la Planta Tratadora de Aguas Residuales es similar al que se hizo con Alumbrado P&uacute;blico y en donde el municipio se hace cargo por completo de la prestaci&oacute;n de esos servicios p&uacute;blicos.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tomara municipio de Hermosillo control de la PTAR: Alcaldesa<\/p>\n","protected":false},"author":1,"featured_media":140355,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[1579],"class_list":["post-140354","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-celida-lopez"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2021\/03\/1616622978_PTAR.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/140354","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=140354"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/140354\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/140355"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=140354"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=140354"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=140354"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}