{"id":137770,"date":"2021-05-06T13:50:04","date_gmt":"2021-05-06T13:50:04","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2021\/05\/06\/respaldan-proyecto-de-anabel-acosta-en-el-tianguis-de-la-michoacan\/"},"modified":"2021-05-06T13:50:04","modified_gmt":"2021-05-06T13:50:04","slug":"respaldan-proyecto-de-anabel-acosta-en-el-tianguis-de-la-michoacan","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2021\/05\/06\/respaldan-proyecto-de-anabel-acosta-en-el-tianguis-de-la-michoacan\/","title":{"rendered":"Respaldan proyecto de Anabel Acosta en el tianguis de la Michoacan"},"content":{"rendered":"<p>CIUDAD OBREG&Oacute;N.- Con gente de trabajo como los tianguistas de la Michoac&aacute;n dialog&oacute; este domingo Anabel Acosta, candidata de la Alianza Va X Sonora, cercana, alegre y motivada la aspirante a la alcald&iacute;a de Cajeme les dijo que siempre estar&aacute; de su lado.<\/p>\n<p>Y entre sus primeras acciones a su favor les arreglar&aacute; los ba&ntilde;os, instalar&aacute; pavimento y seguir&aacute; impulsado el comercio local cuando llegue a la Presidencia Municipal.<\/p>\n<p>&#8220;La gente aqu&iacute; es bien chambeadora, desde hace mucho tiempo, est&aacute;n avanzando y son bien organizados&#8221;, agreg&oacute;, &#8220;son emprendedores, con negocios que empezaron los pap&aacute;s y contin&uacute;an los hijos, por eso trabajar&aacute;n en conjunto&#8221;.<\/p>\n<p>&#8220;Yo voy a estar con ellos, los voy a escuchar y estar presente, aqu&iacute; los tiangueros van a tener una Presidenta Municipal muy presente&#8221;, enfatiz&oacute; Anabel Acosta.<\/p>\n<p>Fueron distintos locales comerciales los que visit&oacute; en este domingo la Candidata de la Alianza Va X Sonora, de los cuales subsisten 222 familias.<\/p>\n<p>Edelmira Galv&aacute;n, quien trabaja desde hace 25 a&ntilde;os en el Tianguis de la Michoac&aacute;n, precis&oacute; que necesitan pavimento dentro de esta Plaza Comercial, lo cual beneficia no solo a los vendedores sino a los compradores.<\/p>\n<p>El cari&ntilde;o tambi&eacute;n se lo hicieron saber Rosario Jocobi&nbsp; y Mar&iacute;a, &#8220;se le quiere mucho&#8221;, le comentaron, &#8220;y yo a ustedes&#8221;, contest&oacute; la Candidata, agradecida por la buena vibra.<\/p>\n<p>&#8220;Las mujeres somos luchonas y trabajadoras por el pueblo, Dios te bendiga Anabel&#8221;, motivada le coment&oacute; Ofelia Ortega, quien tiene m&aacute;s de 20 a&ntilde;os vendiendo en el Tianguis.<\/p>\n<p>A usted s&iacute; le vamos a dar el apoyo porque necesitamos un cambio real, ocupamos una mujer Presidenta porque nos entiende, expres&oacute; Elo&iacute;sa, vendedora de frutas desde hace 20 a&ntilde;os.<\/p>\n<p>Vista tambi&eacute;n el Deportivo<\/p>\n<p>El deporte es un impulsor para fomentar la convivencia familiar, dijo Anabel Acosta al presenciar un juego de b&eacute;isbol efectuado en el N&aacute;inari 2000, no solo es una fiesta, hielera y comida sino que los deportes generan una serie de valores comunitarios, precis&oacute; la Candidata de la Alianza Va X Sonora.<\/p>\n<p>Acompa&ntilde;ada por su padre Ra&uacute;l Acosta, estuvo en el evento deportivo d&oacute;nde participaron varios equipos de beisbol de la Liga Recreativa Obrera, integrado por j&oacute;venes y adultos del Municipio.<\/p>\n<p>Entre ellos, Los Tigres Anabel Acosta, Los Dodgers, Notar&iacute;a 27, Los Kaskas, Los Dogos Chema, los chicos&nbsp; Diamons, Abarrotes Mariposa, Toros, Chinos Audios,&nbsp; Leones SEO y CEU, acompa&ntilde;ados por Roberto Maldonado, presidente de la Liga Obrera.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Respaldan proyecto de Anabel Acosta en el tianguis de la Michoacan<\/p>\n","protected":false},"author":1,"featured_media":137771,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[174],"tags":[4232],"class_list":["post-137770","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-estatal","tag-anabel-acosta"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2021\/05\/1620334204_2584120210502810253.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/137770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=137770"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/137770\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/137771"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=137770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=137770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=137770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}