{"id":137365,"date":"2021-05-12T19:45:08","date_gmt":"2021-05-12T19:45:08","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2021\/05\/12\/con-tecnologia-mejorara-seguridad-de-hermosillenses-tono-astiazaran\/"},"modified":"2021-05-12T19:45:08","modified_gmt":"2021-05-12T19:45:08","slug":"con-tecnologia-mejorara-seguridad-de-hermosillenses-tono-astiazaran","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2021\/05\/12\/con-tecnologia-mejorara-seguridad-de-hermosillenses-tono-astiazaran\/","title":{"rendered":"Con tecnologia mejorara seguridad de hermosillenses : Tono Astiazaran"},"content":{"rendered":"<p>Hermosillo, Sonora, mayo 12 de 2021.- Innovar en la lucha contra la inseguridad con apoyo de tecnolog&iacute;a es uno de los puntos m&aacute;s importantes en el programa de gobierno de Antonio &ldquo;To&ntilde;o&rdquo; Astiazar&aacute;n, candidato a la presidencia municipal de Hermosillo de &ldquo;Va por Sonora&rdquo;.<\/p>\n<p>&nbsp;<\/p>\n<p>En una charla al estilo Ted Talk donde tuvo de invitado al CEO de QTA AeroSpace y ex colaborador de Tesla y de la NASA, Arthur&nbsp; Galarza, &ldquo;To&ntilde;o&rdquo; Astiazar&aacute;n habl&oacute; sobre c&oacute;mo planea revertir la situaci&oacute;n de inseguridad que se vive en Hermosillo, una de las principales preocupaciones de los habitantes.<\/p>\n<p>&nbsp;<\/p>\n<p>Con un enfoque innovador y con la tecnolog&iacute;a como gran aliado, el combate a la inseguridad pasa por lograr eficientar el gasto de la polic&iacute;a municipal, eficientar su servicio e invertir en mayores unidades policiacas, ya que actualmente s&oacute;lo hay 120 patrullas para los 100 sectores de Hermosillo, cuando lo requerido son 300 unidades.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Requerimos de 300 patrullas y actualmente s&oacute;lo hay 120. Para tener una presencia en los 100 sectores que nos permita tener presencia constante y dar respuesta oportuna a todos los reportes ciudadanos, necesitamos 300 unidades.<\/p>\n<p>&nbsp;<\/p>\n<p>Hemos visto que en varias colonias no hay respuesta, por lo que nuestro objetivo es poner la tecnolog&iacute;a al servicio de la familia para eficientar el gasto del gobierno en la polic&iacute;a y asegurar un tiempo de respuesta de las fuerzas de la autoridad a los hermosillenses&rdquo;, se&ntilde;al&oacute; &ldquo;To&ntilde;o&rdquo; Astiazar&aacute;n.<\/p>\n<p>&nbsp;<\/p>\n<p>Por eso, la creaci&oacute;n de una aplicaci&oacute;n m&oacute;vil para que todos los ciudadanos tengan acceso a ello y puedan hacer su reporte, conocer al polic&iacute;a que los atender&aacute;, saber su tiempo de espera y monitorear su actividad, es una forma de innovar y disminuir la inseguridad capitalina.&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Por su parte, el CEO de QTA AeroSpace, se&ntilde;al&oacute; que la trayector&iacute;a de Antonio Astiazar&aacute;n era intachable y que sab&iacute;a de su visi&oacute;n innovadora para resolver problemas sociales y llevar a Hermosillo al futuro.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Es alguien que se prepar&oacute; desde hace mucho tiempo y que siempre ha mostrado inter&eacute;s por estos temas, por el uso de la tecnolog&iacute;a para el bien com&uacute;n. Es posible un cambio buscando soluciones innovadoras&rdquo;, se&ntilde;al&oacute; Arthur Galarza.<\/p>\n<p>&nbsp;<\/p>\n<p>Ciudad inteligente<\/p>\n<p>&nbsp;<\/p>\n<p>A su vez, el candidato de la Alianza &ldquo;Va por Sonora&rdquo;, se&ntilde;al&oacute; que su intensi&oacute;n es convertir a Hermosillo en una ciudad inteligente, una ciudad solar que aproveche las energ&iacute;as alternativas y que se ahorre gasto del municipio con ellas.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Nuestra idea es hacer de Hermosillo una ciudad solar, lograr producir nuestra propia energ&iacute;a y utilizarla en cuatro rubros: Alumbrado p&uacute;blico, Pozos de agua, el acueducto y la planta tratadora de agua y con el ahorro, invertir en infraestructura en paneles solares para los hermosillenses&rdquo;, manifest&oacute; Astiazar&aacute;n.<\/p>\n<p>&nbsp;<\/p>\n<p>En el siglo 21, donde la tecnolog&iacute;a se ha convertido en el epicentro del desarrollo urbano, es vital dar ese paso, siempre de la mano con el talento de los j&oacute;venes y en consonancia con las humanidades y el arte para lograr una verdadera innovaci&oacute;n.<\/p>\n<p>&nbsp;<\/p>\n<p>&ldquo;Vamos a tener una ciudad inteligente con un gobierno responsable e innovador, vamos a so&ntilde;ar para ser mejores y lo vamos a lograr&rdquo;, finaliz&oacute; &ldquo;To&ntilde;o&rdquo; Astiazar&aacute;n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Con tecnologia mejorara seguridad de hermosillenses : Tono Astiazaran<\/p>\n","protected":false},"author":1,"featured_media":137366,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[6340],"class_list":["post-137365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-too-astiazaran"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2021\/05\/1620873908_WhatsAppImage2021-05-12at16.29.19.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/137365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=137365"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/137365\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/137366"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=137365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=137365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=137365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}