{"id":135335,"date":"2021-06-15T14:18:00","date_gmt":"2021-06-15T14:18:00","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2021\/06\/15\/eu-supera-las-600-mil-muertes-por-covid\/"},"modified":"2021-06-15T14:18:00","modified_gmt":"2021-06-15T14:18:00","slug":"eu-supera-las-600-mil-muertes-por-covid","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2021\/06\/15\/eu-supera-las-600-mil-muertes-por-covid\/","title":{"rendered":"EU supera las 600 mil muertes por covid"},"content":{"rendered":"<p><strong style=\"margin: 0px;padding: 0px\">Estados Unidos super&oacute; las 600 mil muertes por covid-19<\/strong>, una cifra que llega ante los avances en la campa&ntilde;a de vacunaci&oacute;n, seg&uacute;n el recuento independiente de la Universidad Johns Hopkins.<\/p>\n<p>A las 13:00 horas, el contador de la universidad registraba un total de 600 mil 012 fallecimientos por el virus desde que empez&oacute; la pandemia en Estados Unidos, el pa&iacute;s que m&aacute;s muertes ha registrado por covid-19 del mundo.<\/p>\n<p>El n&uacute;mero de contagios asciende a casi 33.5 millones, tambi&eacute;n la cifra m&aacute;s alta del mundo, seguida por la India y Brasil.<\/p>\n<div id=\"outstream_article\" data-id=\"106\" data-m=\"{&quot;i&quot;:106,&quot;p&quot;:104,&quot;n&quot;:&quot;article-inlineOutstreamAd&quot;,&quot;t&quot;:&quot;inlineOutstreamAd&quot;,&quot;o&quot;:2}\">&nbsp;<\/div>\n<p><strong style=\"margin: 0px;padding: 0px\">El 54.4 % del total de la poblaci&oacute;n adulta de Estados Unidos (m&aacute;s de 140 millones de personas) est&aacute; ya completamente vacunado<\/strong>, y el 64.5 % (166,5 millones) ha recibido al menos una dosis, de acuerdo al conteo de los Centros de Control y Prevenci&oacute;n de Enfermedades (CDC, en ingl&eacute;s).<\/p>\n<p>El presidente Joe Biden se ha marcado como meta que el 4 de julio, fecha en la que se celebra la festividad del D&iacute;a de la Independencia, el 70 % de los adultos haya sido inoculado con al menos una dosis de las vacunas.&nbsp;<span style=\"margin: 0px;padding: 0px\">No obstante, las autoridades reconocen la preocupaci&oacute;n para alcanzar ese objetivo ante la ralentizaci&oacute;n en las inoculaciones en las &uacute;ltimas semanas, ya que la media diaria ha ca&iacute;do a apenas un mill&oacute;n de dosis frente a los m&aacute;s de tres millones administradas a finales de abril.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>La campa&ntilde;a de vacunaci&oacute;n presenta una gran disparidad por regiones: mientras que estados como Massachusetts, Connecticut y Nueva Jersey tienen ya a m&aacute;s de dos tercios de su poblaci&oacute;n completamente vacunada, otros como Alabama, Georgia y Luisiana solo han inmunizado por completo a poco m&aacute;s de un tercio.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EU supera las 600 mil muertes por covid<\/p>\n","protected":false},"author":1,"featured_media":135336,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[182],"tags":[6854],"class_list":["post-135335","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacional","tag-covid-19"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2021\/06\/1623791880_1210331623777000muertes_eu_ap.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/135335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=135335"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/135335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/135336"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=135335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=135335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=135335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}