{"id":128360,"date":"2021-11-16T14:06:53","date_gmt":"2021-11-16T14:06:53","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2021\/11\/16\/implementa-sat-programa-de-fila-virtual\/"},"modified":"2021-11-16T14:06:53","modified_gmt":"2021-11-16T14:06:53","slug":"implementa-sat-programa-de-fila-virtual","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2021\/11\/16\/implementa-sat-programa-de-fila-virtual\/","title":{"rendered":"Implementa SAT programa de Fila Virtual"},"content":{"rendered":"<p class=\"MsoNormal\"><span lang=\"ES\">El Servicio de Administraci&oacute;n Tributaria (SAT) implementar&aacute; en todo el pa&iacute;s, el dentro del programa &ldquo;Fila-Virtual&rdquo;.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">La propia dependencia federal, ha dado a conocer que ese programa, es una forma de agendar citas autom&aacute;ticamente en CitaSAT, lo cual es b&aacute;sicamente una herramienta para reservar, consultar y cancelar una cita en cualquier modulo de manera segura, eficaz e inmediata sin la necesidad de recurrir a intermediarios o terceras personas. <\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">Dicho aplicativo puede ser consultado en el portal&nbsp;<\/span><a href=\"http:\/\/www.sat.gob.mx\/\" target=\"_blank\" rel=\"noopener\"><span lang=\"ES\">www.sat.gob.mx<\/span><\/a><span lang=\"ES\">, o bien en la direcci&oacute;n electr&oacute;nica siguiente de&nbsp;<\/span><a href=\"https:\/\/citas.sat.gob.mx\/\" target=\"_blank\" rel=\"noopener\"><span lang=\"ES\">citas.sat.gob.mx\/<\/span><\/a><span class=\"MsoHyperlink\"><span lang=\"ES\">y el funcionamiento de esa fila virtual, ayudar&aacute; a los contribuyentes a recibir una cita autom&aacute;ticamente, en el momento que exista disponibilidad<\/span><\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">Finalmente, autoridades del SAT, dieron a conocer que se trata de un programa en el cual los contribuyentes tienen que formarse en la ventanilla de la Fila Virtual&rdquo;, donde se les otorgar&aacute; el turno, por lo que una vez que haya disponibilidad, se les enviar&aacute; la cita correspondiente al correo registrado, la cual deber&aacute; aceptar o rechazar dentro de las 24 horas siguientes.<\/span><\/p>\n<p class=\"MsoNormal\"><span lang=\"ES\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Implementa SAT programa de Fila Virtual<\/p>\n","protected":false},"author":1,"featured_media":128361,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[1211],"class_list":["post-128360","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-sat"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2021\/11\/1637096813_fila-virtual-sat-como-sacar-cita.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/128360","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=128360"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/128360\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/128361"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=128360"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=128360"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=128360"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}