{"id":126860,"date":"2021-12-10T07:06:25","date_gmt":"2021-12-10T07:06:25","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2021\/12\/10\/quiere-cimarrones-de-sonora-iniciar-fuerte-el-torneo\/"},"modified":"2021-12-10T07:06:25","modified_gmt":"2021-12-10T07:06:25","slug":"quiere-cimarrones-de-sonora-iniciar-fuerte-el-torneo","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2021\/12\/10\/quiere-cimarrones-de-sonora-iniciar-fuerte-el-torneo\/","title":{"rendered":"Quiere Cimarrones de Sonora iniciar fuerte el torneo"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"text-align: justify;line-height: 150%\"><span lang=\"ES\">Cimarrones de Sonora se encuentra en su primera semana de pretemporada para el Torneo Clausura 2022, bajo la direcci&oacute;n del profesor Gabriel Pereyra, quien estar&aacute; al mando del equipo sonorense en Liga de Expansi&oacute;n por cuarto torneo consecutivo. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;line-height: 150%\"><span lang=\"ES\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;line-height: 150%\"><span lang=\"ES\">Pereyra inici&oacute; la primera etapa de pretemporada con una charla de bienvenida a jugadores y al resto del cuerpo t&eacute;cnico, donde se trazaron los objetivos para el pr&oacute;ximo a&ntilde;o. Luego de que el equipo se sometiera a los debidos ex&aacute;menes m&eacute;dicos, comenzaron con d&iacute;as de intenso trabajo f&iacute;sico. &ldquo;Los chicos se han mostrado de muy buena gana, buena condici&oacute;n y eso va a ser que iniciemos el torneo siendo competitivos&rdquo;, coment&oacute; el Director T&eacute;cnico de Cimarrones. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;line-height: 150%\"><span lang=\"ES\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;line-height: 150%\"><span lang=\"ES\">El &ldquo;M&iacute;stico&rdquo; tambi&eacute;n destac&oacute; que se trata de una pretemporada muy integral donde adem&aacute;s de la parte f&iacute;sica, se ven conceptos t&eacute;cnicos y t&aacute;cticos con el fin de estar listos para presentar un equipo altamente competitivo desde la primera fecha. &ldquo;Es por eso que estamos trabajando ahora doble sesi&oacute;n en estos primeros d&iacute;as como para poder sumar minutos de entrenamiento y llegar mejor al inicio del torneo&rdquo;. <\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;line-height: 150%\"><span lang=\"ES\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;line-height: 150%\"><span lang=\"ES\">A la espera de que se presente el calendario oficial para el Torneo Clausura 2022, Gabriel Pereyra reiter&oacute; su compromiso con el equipo y la afici&oacute;n sonorense. &ldquo;Hay que trabajar, hay que redoblar esfuerzos, hay que volver a insistir y estar preparados&rdquo;. El T&eacute;cnico de Cimarrones expres&oacute; su alegr&iacute;a por estar de vuelta en Hermosillo y reafirm&oacute; la confianza en sus jugadores. &ldquo;Nosotros confiamos en que tenemos muy buen plantel, muy buenos jugadores y que podemos ser muy competitivos el pr&oacute;ximo torneo&rdquo;.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;line-height: 150%\"><span lang=\"ES\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify;line-height: 150%\"><span lang=\"ES\">El d&iacute;a 17 de diciembre el equipo partir&aacute; a su gira de pretemporada a Mazatl&aacute;n y Guadalajara, donde sostendr&aacute; partidos amistosos con el representativo sub 20 de Mazatl&aacute;n FC y posteriormente con el Club Deportivo Tapat&iacute;o. <\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quiere Cimarrones de Sonora iniciar fuerte el torneo<\/p>\n","protected":false},"author":1,"featured_media":126861,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[188],"tags":[250],"class_list":["post-126860","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","tag-cimarrones-sonora"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2021\/12\/1639145185_Entrenamientoo.JPG","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/126860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=126860"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/126860\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/126861"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=126860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=126860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=126860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}