{"id":125444,"date":"2022-01-12T13:49:54","date_gmt":"2022-01-12T13:49:54","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2022\/01\/12\/invitan-a-acudir-a-las-bibliotecas-publicas-de-hermosillo\/"},"modified":"2022-01-12T13:49:54","modified_gmt":"2022-01-12T13:49:54","slug":"invitan-a-acudir-a-las-bibliotecas-publicas-de-hermosillo","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2022\/01\/12\/invitan-a-acudir-a-las-bibliotecas-publicas-de-hermosillo\/","title":{"rendered":"Invitan a acudir a las bibliotecas publicas de Hermosillo"},"content":{"rendered":"<p class=\"MsoNormal\"><span>Hace una invitaci&oacute;n el Instituto Municipal de Cultura y Arte (IMCA) de Hermosillo a la comunidad infantil y juvenil a las bibliotecas p&uacute;blicas que hay en el &aacute;rea urbana y rural para realizar actividades acad&eacute;micas y recreativas.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Czarina Olo&ntilde;o Morales, Sub directora de patrimonio cultural y bibliotecas del IMCA Hermosillo, se&ntilde;al&oacute; que en el municipio hay 10 bibliotecas p&uacute;blicas, las cuales se mantienen abiertas, siguiendo los protocolos que exige la Secretar&iacute;a de Salud y con aforos actualmente del 60 por ciento debido a que la ciudad se encuentra en color naranja en el sem&aacute;foro epidemiol&oacute;gico.<\/span><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><strong><span>&ldquo;Por efectos de la pandemia por algun tiempo se detuvo un poco pero no dejamos de tener actividades virtuales en la pagina de bibliotecas IMCA Hermosillo, ah&iacute; tenemos rese&ntilde;as, lecturas, cine club en casa y otro tipo de actividades como lectura creativa. Ahorita ya est&aacute;n las bibliotecas reactivadas, cuidando todos los protocolos, pueden acudir todas las ni&ntilde;as, ni&ntilde;os y j&oacute;venes para realizar sus actividades yanto acad&eacute;micas como literarias&rdquo;, cont&oacute;.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\"><span>&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\"><span>Record&oacute;, que en el &aacute;rea urbana hay 5 bibliotecas y en la rural otras 5, por lo que invit&oacute; a la poblaci&oacute;n a tener en cuenta que esos espacios que el municipio coordina, est&aacute;n trabajando con normalidad en distintos horarios y acatando los protocolos que exigen las autoridades de salud ante la pandemia<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Invitan a acudir a las bibliotecas publicas de Hermosillo<\/p>\n","protected":false},"author":1,"featured_media":125445,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[4279],"class_list":["post-125444","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-imca"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2022\/01\/1642020594_teenagers-reading-book-near-friend_23-2147864012.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/125444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=125444"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/125444\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/125445"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=125444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=125444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=125444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}