{"id":124840,"date":"2022-01-24T06:07:45","date_gmt":"2022-01-24T06:07:45","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2022\/01\/24\/eva-longoria-celebra-sus-raices-mexicanas-con-documental-sobre-2-iconos-del-box\/"},"modified":"2022-01-24T06:07:45","modified_gmt":"2022-01-24T06:07:45","slug":"eva-longoria-celebra-sus-raices-mexicanas-con-documental-sobre-2-iconos-del-box","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2022\/01\/24\/eva-longoria-celebra-sus-raices-mexicanas-con-documental-sobre-2-iconos-del-box\/","title":{"rendered":"Eva Longoria celebra sus raices mexicanas con documental sobre 2 iconos del box"},"content":{"rendered":"<p>Milenio<\/p>\n<p>&nbsp;<\/p>\n<p><strong style=\"margin: 0px;padding: 0px\">Eva Longoria<\/strong>&nbsp;estren&oacute; en el Festival de Sundance el documental&nbsp;<em style=\"margin: 0px;padding: 0px\"><strong style=\"margin: 0px;padding: 0px\">La Guerra Civil<\/strong><\/em>, que repasa la rivalidad entre<strong style=\"margin: 0px;padding: 0px\">&nbsp;los boxeadores &Oacute;scar de la Hoya y Julio C&eacute;sar Ch&aacute;vez<\/strong>, y lo que signific&oacute; para la comunidad mexicana en Estados Unidos.<\/p>\n<blockquote><p>&#8220;<strong style=\"margin: 0px;padding: 0px\">Soy 100 por ciento mexicana y 100 por ciento estadunidense.&nbsp;<\/strong>Al mismo tiempo.&nbsp;<strong style=\"margin: 0px;padding: 0px\">No tienes que elegir<\/strong>&#8220;, asegur&oacute; Longoria en la presentaci&oacute;n del filme, cuya trama repasa&nbsp;<strong style=\"margin: 0px;padding: 0px\">las diferencias que hab&iacute;a entre Ch&aacute;vez, un veterano boxeador mexicano, y De la Hoya, una joven promesa estadunidense de origen mexicano.<\/strong><\/p><\/blockquote>\n<blockquote><p><strong style=\"margin: 0px;padding: 0px\"><br \/><\/strong><\/p><\/blockquote>\n<p>El<strong style=\"margin: 0px;padding: 0px\">&nbsp;momento cumbre de su competencia lleg&oacute; en 1996<\/strong>, cuando el combate que enfrent&oacute; a ambos deportistas dividi&oacute; a la comunidad mexicana entre los que apoyaban a Ch&aacute;vez, una leyenda del boxeo en su pa&iacute;s, y los que se&nbsp;<strong style=\"margin: 0px;padding: 0px\">decantaron por De la Hoya<\/strong>, visto por los otros como un estadounidense ajeno a su cultura.&nbsp;<\/p>\n<blockquote><p>&#8220;Oscar (de la Hoya) y yo hemos sido amigos durante 25 a&ntilde;os y me dijo que&nbsp;<strong style=\"margin: 0px;padding: 0px\">quer&iacute;a que dirigiera el documental sobre el aniversario de la pelea<\/strong>&#8220;, explic&oacute; Longoria durante el coloquio posterior al estreno.<\/p><\/blockquote>\n<p>La actriz y directora afirm&oacute; que a&uacute;n recuerda la divisi&oacute;n cultural que supuso ese combate.<\/p>\n<blockquote><p>&#8220;Hasta mi casa estaba dividida y&nbsp;<strong style=\"margin: 0px;padding: 0px\">pens&eacute; que era interesante analizar ese aspecto<\/strong>&nbsp;porque es algo a lo que a&uacute;n nos enfrentamos como comunidad&#8221;, a&ntilde;adi&oacute;.<\/p><\/blockquote>\n<blockquote>\n<p style=\"margin: 0px 0px 1.9rem;padding: 0px\">Longoria, quien hasta ahora hab&iacute;a dirigido varios proyectos televisivos y cortometrajes, expres&oacute; su amor por el g&eacute;nero documental: &#8220;Es uno de mis medios favoritos.&nbsp;<strong style=\"margin: 0px;padding: 0px\">Me encanta humanizar los problemas<\/strong>&#8220;.<\/p>\n<h2><span style=\"margin: 0px;padding: 0px\">El documental sobre la rivalidad entre D<strong style=\"margin: 0px;padding: 0px\"><span style=\"margin: 0px;padding: 0px\"><strong style=\"margin: 0px;padding: 0px\">e la Hoya y Julio C&eacute;sar Ch&aacute;vez<\/strong><\/span><\/strong><\/span><\/h2>\n<p style=\"margin: 0px 0px 1.9rem;padding: 0px\"><em style=\"margin: 0px;padding: 0px\"><strong style=\"margin: 0px;padding: 0px\">La Guerra Civil<\/strong><\/em>, que Sundance eligi&oacute; como uno de sus filmes inaugurales, est&aacute; rodado mayoritariamente en espa&ntilde;ol e incluye&nbsp;<strong style=\"margin: 0px;padding: 0px\">entrevistas con los dos boxeadores&nbsp;<\/strong>y reflexiones de otros &iacute;conos del mundo latino, como el actor Mario L&oacute;pez.<\/p>\n<p style=\"margin: 0px 0px 1.9rem;padding: 0px\"><strong style=\"margin: 0px;padding: 0px\">Ch&aacute;vez<\/strong>&nbsp;recuerda en la cinta&nbsp;<strong style=\"margin: 0px;padding: 0px\">su infancia humilde en Sonora&nbsp;<\/strong>(norte de M&eacute;xico), donde comenz&oacute; boxear para ganar dinero y ayudar a sus padres,&nbsp;<strong style=\"margin: 0px;padding: 0px\">mientras De la Hoya insiste en que siempre quiso conservar las ra&iacute;ces mexicanas de su familia<\/strong>&nbsp;y profesaba una enorme admiraci&oacute;n por Ch&aacute;vez desde que comenz&oacute; a practicar boxeo impulsado por su padre, con apenas cinco a&ntilde;os.<\/p>\n<blockquote style=\"margin: 0px;padding: 0px\"><p>&#8220;Estaba tan concentrado que nunca me di cuenta del impacto cultural del combate. Pero cuando vi a Ch&aacute;vez, el h&eacute;roe nacional de M&eacute;xico, experiment&eacute; por primera vez esa divisi&oacute;n&#8221;, se&ntilde;al&oacute; De la Hoya durante el coloquio.&nbsp;<\/p><\/blockquote>\n<\/blockquote>\n<blockquote style=\"margin: 0px;padding: 0px\">\n<blockquote><p>&#8220;Tu coraz&oacute;n est&aacute; en M&eacute;xico, en tu cultura, pero tambi&eacute;n amas Estados Unidos, que es de donde eres y te ha ofrecido tantas oportunidades&#8221;, dijo al recordar su experiencia como hijo de inmigrantes.<\/p><\/blockquote>\n<p>Longoria, que subray&oacute; su amistad con De la Hoya, afirm&oacute; que se sinti&oacute; reflejada en el boxeador estadounidense desde joven, cuando su familia segu&iacute;a sus combates por televisi&oacute;n en su casa de Texas (Estados Unidos).&nbsp;<strong style=\"margin: 0px;padding: 0px\">&#8220;Me ve&iacute;a a m&iacute; misma en &eacute;l, y mis primos tambi&eacute;n&#8221;<\/strong>, analiz&oacute;.&nbsp;<\/p>\n<\/blockquote>\n","protected":false},"excerpt":{"rendered":"<p>Eva Longoria celebra sus raices mexicanas con documental sobre dos iconos del boxeo<\/p>\n","protected":false},"author":1,"featured_media":124841,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[219],"tags":[1670],"class_list":["post-124840","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-espectaculos","tag-eva-longoria"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2022\/01\/1643029665_eva2-e1642721176449-660x330.png","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/124840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=124840"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/124840\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/124841"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=124840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=124840"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=124840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}