{"id":121739,"date":"2022-03-12T14:02:52","date_gmt":"2022-03-12T14:02:52","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2022\/03\/12\/se-incorporan-nuevos-elementos-al-departamento-de-bomberos-de-hermosillo\/"},"modified":"2022-03-12T14:02:52","modified_gmt":"2022-03-12T14:02:52","slug":"se-incorporan-nuevos-elementos-al-departamento-de-bomberos-de-hermosillo","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2022\/03\/12\/se-incorporan-nuevos-elementos-al-departamento-de-bomberos-de-hermosillo\/","title":{"rendered":"Se incorporan nuevos elementos al Departamento de Bomberos de Hermosillo"},"content":{"rendered":"<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\"><strong>Hermosillo, Sonora; 12 marzo de 2022.-<\/strong>&nbsp;El Departamento de Bomberos de Hermosillo cerrar&aacute; el mes de marzo con 16 nuevos elementos con los que se fortalecen los servicios de la corporaci&oacute;n a la comunidad, confirm&oacute; Juan Francisco Matty Ortega.<\/p>\n<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">El Director de la instituci&oacute;n en la localidad detall&oacute; que recientemente se incorporaron 9 elementos que participaron en la convocatoria emitida desde la administraci&oacute;n municipal anterior, y a la que se le dio puntual seguimiento en la actual, que preside Antonio Astiazar&aacute;n Guti&eacute;rrez.<\/p>\n<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Tambi&eacute;n fueron aprobadas 11 plazas laborales extras, de las cuales 7 corresponden a Bomberos de l&iacute;nea, 2 a operadores de comunicaci&oacute;n y 2 a mec&aacute;nicos especializados en motores diesel, para atender a un parque vehicular que ha crecido, abund&oacute;.<\/p>\n<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Confirm&oacute; que el lunes 07 de marzo se dio a conocer el resultado del proceso de selecci&oacute;n del personal entrante, e inform&oacute; que en la actualidad se cuenta con 156 tragah&uacute;mos y se proyecta elevar esa cifra a 170 en marzo, cuando concluya est&aacute; din&aacute;mica de ingresos nuevos.<\/p>\n<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Los criterios y protocolos de contrataci&oacute;n est&aacute;n establecidos en el reglamento de la instituci&oacute;n y del &aacute;rea de Recursos Humanos del Ayuntamiento, incluye una convocatoria que aprueba la Comisi&oacute;n de Honor y Escalaf&oacute;n para el servicio de Bomberos, explic&oacute; el comandante Matty Ortega.<\/p>\n<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Los criterios son los mismos para aspirantes mujeres y hombres y consideran sus conocimientos en cuanto a control de incendios y capacidades f&iacute;sicas, adem&aacute;s de que como apoyo todos participan en un curso proped&eacute;utico, para refrescar sus competencias previo a una evaluaci&oacute;n, coment&oacute;.<\/p>\n<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">Revel&oacute; que en previsi&oacute;n del crecimiento de la ciudad el Gobierno Municipal podr&iacute;a promover nuevas plazas para el 2023.<\/p>\n<p style=\"color: #222222;font-family: Arial, Helvetica, sans-serif;font-size: small\">&ldquo;Est&aacute; creciendo el &aacute;rea urbanizada, lo que son las colonias habitadas, pero tambi&eacute;n se est&aacute;n desarrollando parques industriales y otros servicios en materia econ&oacute;mica, para lo cual debemos estar preparados&rdquo;, concluy&oacute;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se incorporan nuevos elementos al Departamento de Bomberos de Hermosillo<\/p>\n","protected":false},"author":1,"featured_media":121740,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[5905],"class_list":["post-121739","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-bomberos-hmo"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2022\/03\/1647118972_maty.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/121739","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=121739"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/121739\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/121740"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=121739"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=121739"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=121739"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}