{"id":119652,"date":"2022-04-14T08:31:31","date_gmt":"2022-04-14T08:31:31","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2022\/04\/14\/sesiones-de-consejo-general-del-iee-sonora-contaran-con-interpretacion-de-lengua\/"},"modified":"2022-04-14T08:31:31","modified_gmt":"2022-04-14T08:31:31","slug":"sesiones-de-consejo-general-del-iee-sonora-contaran-con-interpretacion-de-lengua","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2022\/04\/14\/sesiones-de-consejo-general-del-iee-sonora-contaran-con-interpretacion-de-lengua\/","title":{"rendered":"Sesiones de Consejo General del IEE Sonora contaran con interpretacion de Lengua"},"content":{"rendered":"<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">Hermosillo, Sonora. Abril 14,2022.- El Consejo General del IEE Sonora incorpor&oacute;, a partir de la sesi&oacute;n ordinaria celebrada este d&iacute;a, la interpretaci&oacute;n con Lengua de Se&ntilde;as Mexicana (LSM) garantizando de esta forma el derecho a la informaci&oacute;n a las personas con discapacidad auditiva.8<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">El Consejero Presidente Nery Ruiz Arvizu agradeci&oacute; a integrantes de la Comunidad Sorda de Hermosillo su presencia en esta sesi&oacute;n, y destac&oacute; el compromiso de este Instituto a favor de la inclusi&oacute;n.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">&ldquo;Las y los consejeros, con la participaci&oacute;n tambi&eacute;n de las y los representantes de los partidos pol&iacute;ticos, nos sumamos a este proyecto que hoy es una realidad para llegar a quienes necesitan acceder a informaci&oacute;n, que se sientan escuchados y valorados. La democracia tambi&eacute;n se trata de eso&rdquo;, expres&oacute;.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><strong><span style=\"font-family: Arial, sans-serif\">Aprueban C&oacute;digo de Conducta<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">En la sesi&oacute;n ordinaria de este d&iacute;a, las y los Consejeros Electorales aprobaron por unanimidad el C&oacute;digo de Conducta del Instituto Estatal Electoral y de Participaci&oacute;n Ciudadana de Sonora, de conformidad con los Lineamientos para la emisi&oacute;n del C&oacute;digo de &Eacute;tica a que se refiere el art&iacute;culo 16 de la Ley General de Responsabilidades Administrativas aprobados por el Comit&eacute; Coordinador del Sistema Nacional Anticorrupci&oacute;n.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">En este c&oacute;digo, se espec&iacute;fica, de manera puntual y concreta, la forma en que las personas servidoras p&uacute;blicas aplicar&aacute;n los principios, valores y reglas de integridad que se incluyen en este documento que ser&aacute; de observancia general y obligatoria.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><strong><span style=\"font-family: Arial, sans-serif\">Designan autoridad de primer contacto conciliadora, instructora y resolutora del protocolo para prevenir, atender, sancionar y reparar el hostigamiento y acoso sexual y laboral.<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">El Conejo General design&oacute; a la Direcci&oacute;n Ejecutiva de Paridad e Igualdad de G&eacute;nero como autoridad de primer contacto responsable de la atenci&oacute;n y orientaci&oacute;n de la persona funcionaria agraviada, quejosa o denunciante, en los conflictos laborales; a la Direcci&oacute;n Ejecutiva de Asuntos Jur&iacute;dicos, como autoridad instructora y conciliadora del procedimiento sancionador correspondiente a la Secretar&iacute;a Ejecutiva, como autoridad resolutora del mismo procedimiento.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">De igual forma, las y los Consejeros Electorales determinaron que ser&aacute; la Junta General Ejecutiva la autoridad competente para resolver el recurso de inconformidad del procedimiento sancionador correspondiente.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><strong><span style=\"font-family: Arial, sans-serif\">Se Sobresee Procedimiento Ordinario Sancionador<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">A propuesta de la Comisi&oacute;n Permanente de Denuncias, el Consejo General aprob&oacute; el sobreseimiento de la denuncia interpuesta por la ciudadana Josefina Monta&ntilde;o Aguirre, identificada con la clave&nbsp;<strong>IEE\/POS-01\/2022<\/strong>.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><strong><span style=\"font-family: Arial, sans-serif\">Validan Reglamento de Comit&eacute;s Editoriales<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">Durante el desarrollo de esta sesi&oacute;n, se aprob&oacute; el Reglamento para la conformaci&oacute;n y funcionamiento de los Comit&eacute;s Editoriales del Instituto Estatal Electoral y de Participaci&oacute;n Ciudadana de Sonora, &oacute;rganos que se integrar&aacute;n para dar seguimiento a los respectivos proyectos editoriales de este Instituto, de conformidad con lo establecido en los Lineamientos Editoriales aprobados en el Acuerdo&nbsp;<strong>CG221\/2022<\/strong><\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><strong><span style=\"font-family: Arial, sans-serif\">Direcci&oacute;n Ejecutiva de Fiscalizaci&oacute;n presenta informes de organizaciones que buscan constituirse como PPL<\/span><\/strong><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif;color: black;background-image: initial;background-position: initial;background-size: initial;background-repeat: initial\">La Direcci&oacute;n Ejecutiva de Fiscalizaci&oacute;n, present&oacute; el informe relativo a los meses de enero y febrero, respecto del avance en las revisiones de los informes mensuales presentados por las Organizaciones Ciudadanas y de su cumplimiento a las disposiciones de los Lineamientos para la Fiscalizaci&oacute;n de las Organizaciones Ciudadanas que pretenden constituirse como Partidos Pol&iacute;ticos Locales.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><strong><span style=\"font-family: Arial, sans-serif\">Secretar&iacute;a Ejecutiva presenta informes<\/span><\/strong><\/p>\n<p><span style=\"font-size: 11pt;font-family: Arial, sans-serif;color: black;border: 1pt none windowtext;padding: 0cm\">La Secretar&iacute;a Ejecutiva rindi&oacute; el informe de las denuncias en materia de Violencia Pol&iacute;tica contra las Mujeres en Raz&oacute;n de G&eacute;nero, adem&aacute;s del informe en relaci&oacute;n con medidas cautelares y protecci&oacute;n en la misma materia, en t&eacute;rminos del art&iacute;culo 44 del Reglamento para la Sustanciaci&oacute;n de los Reg&iacute;menes Sancionadores en el tema de Violencia Pol&iacute;tica contra las Mujeres en Raz&oacute;n de G&eacute;nero.&nbsp;<\/span><\/p>\n<p><span style=\"font-size: 11pt;font-family: Arial, sans-serif;color: black;border: 1pt none windowtext;padding: 0cm\">&nbsp;<\/span><\/p>\n<p><span style=\"font-size: 11pt;font-family: Arial, sans-serif;color: black;border: 1pt none windowtext;padding: 0cm\">En esta sesi&oacute;n ordinaria, se puso a disposici&oacute;n por parte de la Secretar&iacute;a Ejecutiva el informe de cumplimiento de los acuerdos del Consejo General correspondiente al periodo comprendido del 15 de febrero al 08 de abril de 2022, en atenci&oacute;n al art&iacute;culo 123, fracci&oacute;n III de la LIPEES.&nbsp;<\/span><\/p>\n<p><span style=\"font-size: 11pt;font-family: Arial, sans-serif;color: black\">&nbsp;<\/span><\/p>\n<p><span style=\"font-size: 11pt;font-family: Arial, sans-serif;color: black;border: 1pt none windowtext;padding: 0cm\">De igual forma, la Secretar&iacute;a Ejecutiva present&oacute; en esta sesi&oacute;n presencial ordinaria,&nbsp; la cuenta de peticiones y diligencias practicadas en ejercicio de funci&oacute;n de Oficial&iacute;a Electoral, as&iacute; como los informes sobre la cuenta de medios de impugnaci&oacute;n, resoluciones dictadas por los tribunales electorales adem&aacute;s de la cuenta de peticiones y consultas que se han presentado, con fundamento en las fracciones VI y VII del art&iacute;culo 123, de la Ley de Instituciones y Procedimientos Electorales para el Estado de Sonora.&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">&nbsp;<\/span><\/p>\n<p class=\"MsoNormal\" style=\"margin: 0cm 0cm 8pt;color: #222222;text-align: justify;line-height: 15.6933px;font-size: 11pt;font-family: Calibri, sans-serif\"><span style=\"font-family: Arial, sans-serif\">Los informes y acuerdos aprobados en la sesi&oacute;n ordinaria de este d&iacute;a, est&aacute;n disponibles para su consulta en:&nbsp;<a style=\"color: #0563c1\" href=\"https:\/\/www.ieesonora.org.mx\/estructura\/organos_centrales\/consejo_general\/acuerdos\" target=\"_blank\" data-saferedirecturl=\"https:\/\/www.google.com\/url?q=https:\/\/www.ieesonora.org.mx\/estructura\/organos_centrales\/consejo_general\/acuerdos&amp;source=gmail&amp;ust=1649990565441000&amp;usg=AOvVaw2QHV3-HJLCm_9QRBZwcuFe\" rel=\"noopener\">https:\/\/www.ieesonora.org.mx\/estructura\/organos_centrales\/consejo_general\/acuerdos<\/a><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sesiones de Consejo General del IEE Sonora contaran con interpretacion de Lengua de Senas Mexicana<\/p>\n","protected":false},"author":1,"featured_media":119653,"comment_status":"","ping_status":"","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[2203],"class_list":["post-119652","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-iee"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2022\/04\/1649950291_00.jpeg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/119652","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=119652"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/119652\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/119653"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=119652"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=119652"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=119652"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}