{"id":11022,"date":"2014-10-13T19:44:59","date_gmt":"2014-10-13T19:44:59","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/10\/13\/ayuda-en-el-ro-sonora-es-lenta-e-insuficiente-lorenia-valles\/"},"modified":"2014-10-13T19:44:59","modified_gmt":"2014-10-13T19:44:59","slug":"ayuda-en-el-ro-sonora-es-lenta-e-insuficiente-lorenia-valles","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/10\/13\/ayuda-en-el-ro-sonora-es-lenta-e-insuficiente-lorenia-valles\/","title":{"rendered":"Ayuda en el R&iacute;o Sonora es lenta e insuficiente: Lorenia Valles"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">Hermosillo, Sonora, a 13 Octubre 2014.- &ldquo;El ritmo de avance para atender el asunto del Rio Sonora ha marchado muy lento y por ende los ciudadanos afectados est&aacute;n exigiendo celeridad de parte de las autoridades estatales y federales en la entrega del recurso del fideicomiso especial que se cre&oacute; para ello&rdquo;, se&ntilde;al&oacute; Lorenia Valles Sampedro.<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">&nbsp;<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">La diputada federal perredista manifest&oacute; que durante la comparecencia que sostuvieron con el Secretario del Trabajo y Previsi&oacute;n Social Alfonso Navarrete Prida en su calidad de coordinador de la Comisi&oacute;n del Rio Sonora, adem&aacute;s de escuchar la informaci&oacute;n sobre las actividades y el nivel de avance que los trabajos para reparar el grave da&ntilde;o que ocasion&oacute; Grupo M&eacute;xico, la necesidad urgente de modificar los procedimientos de la entrega de los apoyos y sobre todo los montos considerados para las personas afectada.<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">&nbsp;<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">&ldquo;Los montos que est&aacute;n manejando nos parecen insuficientes, se requieren mayores recursos y adem&aacute;s estamos hablando del da&ntilde;o econ&oacute;mico actual para la poblaci&oacute;n afectada y el otro es el da&ntilde;o que sufrir&aacute;n posteriormente en sus actividades econ&oacute;micas, agropecuarias, turismo o servicio. Por este motivo es que en la comisi&oacute;n especial que se cre&oacute; para atender este caso propusimos el impulsar un programa de los 5 mil millones de pesos para la reactivaci&oacute;n econ&oacute;mica de esa regi&oacute;n y ayudar a remedir la grave situaci&oacute;n econ&oacute;mica que est&aacute;n atravesando m&aacute;s de 22 mil habitantes&rdquo;, extern&oacute;.<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">&nbsp;<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">Detall&oacute; que la molestia que han expresado una gran cantidad de las personas afectadas en el Rio Sonora con la entrega de los recursos del fideicomiso, que en una primera etapa cuenta con un monto de 522 millones de pesos, es debido a que algunos productores agr&iacute;colas se les est&aacute;n entregando montos m&aacute;ximos de 100 mil pesos, a los ganaderos 105 mil pesos y lo que se est&aacute; considerando para las 1,426 unidades econ&oacute;micas afectadas, seg&uacute;n cifras de la Secretaria de Econom&iacute;a. El dinero que se ha entregado realmente no ayuda q reparar completamente los da&ntilde;os, ademas son m&iacute;nimos los recursos que hasta el momento se han destinado para la atenci&oacute;n de la salud de las personas.<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">&nbsp;<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">Valles Sampedro dijo tambi&eacute;n, que es urgente que la federaci&oacute;n explique de una forma m&aacute;s clara el mecanismo que se utilizar&aacute; para la remediaci&oacute;n ambiental, porque a la fecha el comit&eacute; de expertos no han dado a conocer el m&eacute;todo que usaran para llevar a cabo para el saneamiento del &aacute;rea afectada por el grave da&ntilde;o que ocasion&oacute; Grupo M&eacute;xico al contaminar el Rio Sonora, afectando a miles de personas que habitan en esa regi&oacute;n.<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">&nbsp;<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">&ldquo;Nosotros seguimos firmes con base en la ley para que cesen las actividades de la Mina y&nbsp; se cancele la concesi&oacute;n a Grupo Mexico, porque existe una grave violacion&nbsp; a la normatividad y hay s&oacute;lidos argumentos jur&iacute;dicos para poder hacerlo. Vemos tibieza por parte de esta comisi&oacute;n y en especial de los representantes de la Secretaria de econom&iacute;a para llegar a ese punto, pero&nbsp; de nuestra parte no cesaremos en esa pugna y seguiremos exigiendo que se solvente de una manera integral y eficaz la reparaci&oacute;n del da&ntilde;o a toda esta regi&oacute;n&rdquo;, afirm&oacute;.<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">&nbsp;<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">En otro tema, la diputada Lorenia Valles se refiri&oacute; a la Marcha Ciudadana que se llev&oacute; a cabo este fin de semana en Ciudad Obreg&oacute;n, Sonora, se&ntilde;alo que particip&oacute; en por invitaci&oacute;n de la familia de los Yaquis presos y de una representaci&oacute;n amplia de la tribu, a la que hace unos d&iacute;as recibi&oacute; en la c&aacute;mara de diputados, donde present&oacute; un punto de acuerdo para exhortar a las autoridades del Gobierno de Sonora cesen la discriminaci&oacute;n racial y la criminalizaci&oacute;n de la protesta social, y en el que se solicita un proceso apegado a derecho para la liberaci&oacute;n de Mario Luna y Fernando Jim&eacute;nez integrantes de la tribu yaqui, el cual fue aprobado por el pleno.&nbsp;&nbsp;<\/span><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><br style=\"line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px\" \/><span style=\"color: #444444;font-family: Calibri, sans-serif;font-size: 15px;line-height: 21.2999992370605px\">&ldquo;Hay un gran descontento de la ciudadan&iacute;a en Sonora y como muestra fue esa marcha en la cual participaron m&aacute;s de 45 mil personas, estuvimos con las madres de Fernando y Mario, a quienes manifestamos nuestra solidaridad ante esta injusticia. Hemos estado cerca de esta lucha por sus derechos.&nbsp; Creemos que es necesario que en Sonora se establezca una mesa de di&aacute;logo, se respete la ley y no se criminalice a quien no est&eacute; de acuerdo con el gobierno del estado de Sonora&rdquo;, concluy&oacute;.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayuda en el R&iacute;o Sonora es lenta e insuficiente: Lorenia Valles<\/p>\n","protected":false},"author":1,"featured_media":26692,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[742],"class_list":["post-11022","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-lorenia-valles"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2014\/10\/1413254699_Lorenia-Valles-Sampedro-500x331.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/11022","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=11022"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/11022\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/26692"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=11022"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=11022"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=11022"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}