{"id":10773,"date":"2014-10-05T15:49:36","date_gmt":"2014-10-05T15:49:36","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/10\/05\/certifica-ayuntamiento-a-guas-tursticas-para-la-ciudad-de-hermosillo\/"},"modified":"2014-10-05T15:49:36","modified_gmt":"2014-10-05T15:49:36","slug":"certifica-ayuntamiento-a-guas-tursticas-para-la-ciudad-de-hermosillo","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/10\/05\/certifica-ayuntamiento-a-guas-tursticas-para-la-ciudad-de-hermosillo\/","title":{"rendered":"Certifica Ayuntamiento a gu&iacute;as tur&iacute;sticas para la ciudad de Hermosillo"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><strong style=\"margin: 0px\">Hermosillo, Sonora, 5 de octubre de 2014.-&nbsp;La Secretar&iacute;a de Turismo Federal, a trav&eacute;s de la Comisi&oacute;n de Fomento al Turismo del Estado y de Turismo Municipal, certific&oacute; a quince gu&iacute;as de turistas para Hermosillo, a quienes se les entreg&oacute; la credencial en donde se acredita que tienen capacitaci&oacute;n a nivel nacional.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><strong style=\"margin: 0px\">&ldquo;Solo las grandes ciudades de M&eacute;xico cuentan con un cuerpo de gu&iacute;as tur&iacute;sticos con la certificaci&oacute;n que ostentan ahora, porque su trabajo es una distinci&oacute;n y responsabilidad, debido a que les toca atender a nuestros visitantes y hacer que se vayan enamorados del municipio&rdquo;, destac&oacute; el s&iacute;ndico Fernando Miranda Blanco, quien asisti&oacute; al evento en representaci&oacute;n del alcalde Alejandro L&oacute;pez Caballero.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><strong style=\"margin: 0px\">&ldquo;Estas son buenas noticias para nuestra capital por los primeros quince gu&iacute;as de &nbsp;turistas certificados por el gobierno federal en el Estado y capacitados por profesores de la Universidad Estatal de Sonora (UES)&rdquo;, dijo.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><strong style=\"margin: 0px\">La directora de Turismo Municipal, Martha Mada Fraire, agradeci&oacute; a las diferentes instancias que hicieron posible este logro, porque durante 322 horas trabajaron en su preparaci&oacute;n de capacitaci&oacute;n f&iacute;sica y de campo.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><strong style=\"margin: 0px\">Una de las primeras acciones del Gobierno Municipal, coment&oacute;, fue establecer v&iacute;nculos con el sector empresarial y educativo para coordinar esfuerzos, debido a que es necesario contar con personal que a trav&eacute;s de la atenci&oacute;n favoreciera experiencias &uacute;nicas en los turistas.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><strong style=\"margin: 0px\">Por su parte, el director general de Certificaci&oacute;n Tur&iacute;stica de la Secretar&iacute;a de Turismo Federal, No&eacute; Mart&iacute;n V&aacute;zquez P&eacute;rez, indic&oacute; que este es el primer paso de muchos de lo que hay que hacer, de actualizarse cada a&ntilde;o.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><strong style=\"margin: 0px\">Mencion&oacute; que el presidente de la Rep&uacute;blica, Enrique Pe&ntilde;a Nieto, anunci&oacute; que se quiere establecer el Sistema Nacional de Certificaci&oacute;n Tur&iacute;stica para que haya un solo sello de calidad para prestadores de estos servicios de todo el pa&iacute;s, que sean reconocidos por el turista nacional e internacional y que sepan que cumplieron con la NOM -008- SECTUR.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><strong style=\"margin: 0px\">Enfatiz&oacute; que el turismo de inclusi&oacute;n y accesibilidad es un tema muy importante, porque en general no se ofrecen tours para personas con discapacidad, por lo cual felicit&oacute; a una de las gu&iacute;as certificadas este d&iacute;a con conocimiento del lenguaje a se&ntilde;as.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><strong style=\"margin: 0px\">En Hermosillo hay personas que hacen labor de gu&iacute;as de turistas, &eacute;stos no est&aacute;n reconocidos por los gobiernos, dado que no se encuentran certificados y por ende es un trabajo no profesional.<\/strong><\/p>\n<p class=\"ecxMsoNormal\" style=\"margin: 0px 0px 1.35em;line-height: 21.2999992370605px;color: #444444;font-family: Calibri, sans-serif;font-size: 15px;text-align: justify\"><strong style=\"margin: 0px\">En el evento estuvieron tambi&eacute;n el coordinador de la Comisi&oacute;n de Fomento al Turismo del Estado de Sonora, Javier Tapia Camou; el rector de la Universidad Estatal de Sonora, Samuel Espinoza Guill&eacute;n; el diputado federal, Dami&aacute;n Zepeda Vidales y el director general del Instituto Municipal de Cultura, Arte y Turismo (Imcatur), Oscar Mayoral Pe&ntilde;a.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Secretar&iacute;a de Turismo Federal, a trav&eacute;s de la Comisi&oacute;n de Fomento al Turismo del Estado y de Turismo Municipal, certific&oacute; a quince gu&iacute;as de turistas para Hermosillo, a quienes se les entreg&oacute; la credencial <\/p>\n","protected":false},"author":1,"featured_media":26451,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[2622],"class_list":["post-10773","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-guias"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2014\/10\/1412549377_guiasturis.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/10773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=10773"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/10773\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/26451"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=10773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=10773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=10773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}