{"id":10064,"date":"2014-09-06T19:15:11","date_gmt":"2014-09-06T19:15:11","guid":{"rendered":"https:\/\/rnoticias.com.mx\/Portal\/2014\/09\/06\/registra-cfeh-record-de-inversin-de-ms-de-3-mil-mdp\/"},"modified":"2014-09-06T19:15:11","modified_gmt":"2014-09-06T19:15:11","slug":"registra-cfeh-record-de-inversin-de-ms-de-3-mil-mdp","status":"publish","type":"post","link":"https:\/\/rnoticias.com.mx\/Portal\/2014\/09\/06\/registra-cfeh-record-de-inversin-de-ms-de-3-mil-mdp\/","title":{"rendered":"Registra CFEH record de inversi&oacute;n de m&aacute;s de 3 mil mdp"},"content":{"rendered":"<p>Por Redacci&oacute;n<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.2999992370605px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.4545450210571px;text-align: justify\"><strong style=\"line-height: 21.2999992370605px\"><span style=\"line-height: 21.2999992370605px;font-family: Arial, sans-serif\" lang=\"ES-TRAD\">Hermosillo, Sonora, 5 de septiembre de 2014.-<\/span><\/strong><span style=\"line-height: 21.2999992370605px;font-family: Arial, sans-serif\" lang=\"ES-TRAD\">&nbsp;Una cifra record en atracci&oacute;n de inversi&oacute;n privada para el municipio fue lo que registr&oacute; la Comisi&oacute;n de Fomento Econ&oacute;mico de Hermosillo, al captar por medio de la ventanilla empresarial 3 mil 100 millones de pesos en lo que va del presente a&ntilde;o.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.2999992370605px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.4545450210571px;text-align: justify\"><span style=\"line-height: 21.2999992370605px;font-family: Arial, sans-serif\" lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.2999992370605px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.4545450210571px;text-align: justify\"><span style=\"line-height: 21.2999992370605px;font-family: Arial, sans-serif\" lang=\"ES-TRAD\">La directora del &aacute;rea, Lyzeth Salcedo Salinas, se&ntilde;al&oacute; que Hermosillo se ha convertido en un atractivo para la inversi&oacute;n en el pa&iacute;s y gracias a ser un gobierno facilitador para la instalaci&oacute;n de nuevas empresas se logr&oacute; registrar esta cantidad, la cual equivale al triple de lo que se alcanz&oacute; en todo el a&ntilde;o 2012.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.2999992370605px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.4545450210571px;text-align: justify\"><span style=\"line-height: 21.2999992370605px;font-family: Arial, sans-serif\" lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.2999992370605px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.4545450210571px;text-align: justify\"><span style=\"line-height: 21.2999992370605px;font-family: Arial, sans-serif\" lang=\"ES-TRAD\">Esta es una cifra hist&oacute;rica, dijo, porque son 3 mil 100 millones de pesos que se han reflejado en m&aacute;s empleos y en crecimiento de la econom&iacute;a del municipio, todo esto debido a tener un gobierno de alto nivel de gesti&oacute;n, desregulado, con bajos costos de operaci&oacute;n y respuesta r&aacute;pida en los tr&aacute;mites.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.2999992370605px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.4545450210571px;text-align: justify\"><span style=\"line-height: 21.2999992370605px;font-family: Arial, sans-serif\" lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.2999992370605px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.4545450210571px;text-align: justify\"><span style=\"line-height: 21.2999992370605px;font-family: Arial, sans-serif\" lang=\"ES-TRAD\">Salcedo Salinas mencion&oacute; que dichas inversiones han sido aplicadas en plazas comerciales, naves industriales, escuelas, hospitales, hoteles, locales comerciales, abarrotes, restaurantes y empresas de otros giros.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.2999992370605px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.4545450210571px;text-align: justify\"><span style=\"line-height: 21.2999992370605px;font-family: Arial, sans-serif\" lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.2999992370605px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.4545450210571px;text-align: justify\"><span style=\"line-height: 21.2999992370605px;font-family: Arial, sans-serif\" lang=\"ES-TRAD\">La Ventanilla Empresarial de Fomento Econ&oacute;mico inici&oacute; en el a&ntilde;o 2007 y a la fecha ha ampliado los servicios de asesor&iacute;a y gesti&oacute;n de los tr&aacute;mites para la apertura y construcci&oacute;n de empresas de manera gratuita, como lo que se brinda a los empresarios con la certeza jur&iacute;dica, as&iacute; como menores tiempos y costos administrativos.<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.2999992370605px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.4545450210571px;text-align: justify\"><span style=\"line-height: 21.2999992370605px;font-family: Arial, sans-serif\" lang=\"ES-TRAD\">&nbsp;<\/span><\/p>\n<p class=\"ecxMsoNormal\" style=\"line-height: 21.2999992370605px;margin: 0px 0px 1.35em;color: #444444;font-family: Calibri, sans-serif;font-size: 15.4545450210571px;text-align: justify\"><span style=\"line-height: 21.2999992370605px;font-family: Arial, sans-serif\" lang=\"ES-TRAD\">&ldquo;En el mes de agosto se han atendido a mil 102 personas, de las cuales 174 realizaron tr&aacute;mites o solicitaron informaci&oacute;n en el Centro de Desarrollo de Negocios y 928 fueron capacitadas, a trav&eacute;s del programa de formaci&oacute;n empresarial que se lleva a las distintas colonias de la ciudad&rdquo;, agreg&oacute; la funcionaria.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una cifra record en atracci&oacute;n de inversi&oacute;n privada para el municipio fue lo que registr&oacute; la Comisi&oacute;n de Fomento Econ&oacute;mico de Hermosillo, al captar por medio de la ventanilla empresarial 3 mil 100 millones de pesos Una cifra record en atracci&oacute;n <\/p>\n","protected":false},"author":1,"featured_media":25766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[178],"tags":[643],"class_list":["post-10064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-local","tag-fomento-economico"],"jetpack_featured_media_url":"https:\/\/rnoticias.com.mx\/Portal\/wp-content\/uploads\/2014\/09\/1410056111_fomentoecs.jpg","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/10064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/comments?post=10064"}],"version-history":[{"count":0,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/posts\/10064\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media\/25766"}],"wp:attachment":[{"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/media?parent=10064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/categories?post=10064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/rnoticias.com.mx\/Portal\/wp-json\/wp\/v2\/tags?post=10064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}